{"id":12324,"date":"2014-03-15T08:13:38","date_gmt":"2014-03-15T11:13:38","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=12324"},"modified":"2014-12-14T19:50:52","modified_gmt":"2014-12-14T22:50:52","slug":"luciano-torres-vai-investir-dinheiro-do-2o-fem-em-saneamento-e-calcamento-de-santa-rosa","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/luciano-torres-vai-investir-dinheiro-do-2o-fem-em-saneamento-e-calcamento-de-santa-rosa\/","title":{"rendered":"Luciano Torres vai investir dinheiro do 2\u00ba FEM em saneamento e cal\u00e7amento de Santa Rosa"},"content":{"rendered":"<p>O prefeito de Ingazeira Luciano Torres j\u00e1 decidiu o que vai fazer com o segundo Fundo Especial de Apoio aos Munic\u00edpios (FEM) que o Governador Eduardo Campos ir\u00e1 liberar. Falando a R\u00e1dio Cidade FM ontem, Torres disse que priorizar\u00e1 inicialmente aa constru\u00e7\u00e3o de saneamento e calcamentos no Povoado de Santa Rosa. Na 2\u00aa feira durante o Congresso dos Munic\u00edpios o Governador Eduardo Campos assina a libera\u00e7\u00e3o de 250 milh\u00f5es para os munic\u00edpios do estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Ingazeira Luciano Torres j\u00e1 decidiu o que vai fazer com o segundo Fundo Especial de Apoio aos<\/p>\n","protected":false},"author":4,"featured_media":5226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[47,1937,21,1938],"class_list":["post-12324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-destaques","tag-fem","tag-ingazeira","tag-santa-rosa"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/12324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=12324"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/12324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/5226"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=12324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=12324"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=12324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}