{"id":12328,"date":"2014-03-15T08:18:45","date_gmt":"2014-03-15T11:18:45","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=12328"},"modified":"2014-03-15T08:18:45","modified_gmt":"2014-03-15T11:18:45","slug":"inocencio-decide-ser-candidato-a-reeleicao-e-atrapalha-os-planos-politicos-do-primo-sebastiao","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/inocencio-decide-ser-candidato-a-reeleicao-e-atrapalha-os-planos-politicos-do-primo-sebastiao\/","title":{"rendered":"Inoc\u00eancio decide ser candidato \u00e0 reelei\u00e7\u00e3o e atrapalha os planos pol\u00edticos do primo Sebasti\u00e3o"},"content":{"rendered":"<p>O deputado federal Inoc\u00eancio Oliveira (PR) comunicou ontem aos amigos mais pr\u00f3ximos que vai disputar a reelei\u00e7\u00e3o. Em agosto do ano passado, ele deu uma entrevista coletiva na sede do partido para anunciar solenemente que encerraria a vida p\u00fablica quando conclu\u00edsse o atual mandato e apresentou o primo em segundo grau, Sebasti\u00e3o Oliveira, como seu herdeiro pol\u00edtico. Sebasti\u00e3o, de imediato, celebrou um acordo pol\u00edtico com o ex-prefeito de Belmonte, Rog\u00e9rio Le\u00e3o (PR), para ficar com a sua cadeira na Assembleia Legislativa. Rog\u00e9rio montou direitinho sua elei\u00e7\u00e3o, mas com a desist\u00eancia de Inoc\u00eancio de encerrar a vida p\u00fablica vai ter que rever seus planos, a menos que Sebasti\u00e3o decida concorrer tamb\u00e9m \u00e0 C\u00e2mara Federal. Inoc\u00eancio alega que sua candidatura foi uma \u201cexig\u00eancia\u201d do governador e que a maioria dos prefeitos do seu grupo n\u00e3o quer votar em Sebasti\u00e3o, o que \u00e9 contestado por este.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O deputado federal Inoc\u00eancio Oliveira (PR) comunicou ontem aos amigos mais pr\u00f3ximos que vai disputar a reelei\u00e7\u00e3o. Em agosto do<\/p>\n","protected":false},"author":4,"featured_media":2049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[47,4753,487,68,380,410],"class_list":["post-12328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-destaques","tag-eleicoes-2014","tag-inocencio-oliveira","tag-politica","tag-rogerio-leao","tag-sebastiao-oliveira"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/12328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=12328"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/12328\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/2049"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=12328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=12328"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=12328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}