{"id":12341,"date":"2014-03-15T08:38:06","date_gmt":"2014-03-15T11:38:06","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=12341"},"modified":"2014-03-15T08:38:06","modified_gmt":"2014-03-15T11:38:06","slug":"ceagesp-suspende-cobranca-e-fecha-varejao-neste-fim-de-semana","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/ceagesp-suspende-cobranca-e-fecha-varejao-neste-fim-de-semana\/","title":{"rendered":"Ceagesp suspende cobran\u00e7a e fecha &#8216;varej\u00e3o&#8217; neste fim de semana"},"content":{"rendered":"<p><em>Presidente do entreposto diz que vai adiar estacionamento pago.<\/em><\/p>\n<p><em>Manifesta\u00e7\u00e3o contra cobran\u00e7a de estacionamento acabou em tumulto.<\/em><\/p>\n<p>A Companhia de Entreposto e Armaz\u00e9ns Gerais de S\u00e3o Paulo (Ceagesp) suspendeu por tempo indeterminado a cobran\u00e7a de estacionamento e anunciou que n\u00e3o abrir\u00e1 para o p\u00fablico neste fim de semana. Nesta sexta-feira (14), terminou em tumulto uma manifesta\u00e7\u00e3o contra a cobran\u00e7a de estacionamento no entreposto.<\/p>\n<p>Um homem foi baleado e quatro seguran\u00e7as ficaram feridos. Ve\u00edculos foram incendiados e quatro pr\u00e9dios administrativos acabaram vandalizados. &#8220;Foi a\u00e7\u00e3o de bandidos. A soldo de algu\u00e9m? Pode ser&#8221;, disse o presidente da Ceagesp, M\u00e1rio Maurici de Lima Morais. &#8220;Foi a\u00e7\u00e3o de 50 a 100 pessoas. N\u00e3o da maioria (dos caminhoneiros).&#8221;<\/p>\n<p>O presidente disse que o entreposto vai abrir somente para carga e descarga de mercadorias. O varej\u00e3o, que \u00e9 uma feira tradicional, n\u00e3o ir\u00e1 funcionar. &#8220;O mercado precisa ser recuperado. Nesses dias, o afluxo de gente comprador de varejo da sociedade \u00e9 muito grande, ent\u00e3o n\u00f3s vamos interromper no s\u00e1bado e no domingo.&#8221;<\/p>\n<p>A Ceagesp tamb\u00e9m informou que a cobran\u00e7a de estacionamento foi suspensa por tempo indeterminado a partir de segunda-feira. O G1 procurou a C3V (Companhia de Concess\u00f5es em Circula\u00e7\u00e3o Veicular), respons\u00e1vel pelo estacionamento, e aguarda um posicionamento oficial sobre a suspens\u00e3o da cobran\u00e7a.<\/p>\n<p>&#8220;Vamos ter que descobrir, necessariamente, outras formas de financiamento nos pr\u00f3ximos dois, tr\u00eas meses, porque n\u00e3o haver\u00e1 cobran\u00e7a (de estacionamento)&#8221;, disse Morais. &#8220;Se n\u00f3s encontrarmos outra forma de financiamento, poderemos reavaliar a cobran\u00e7a. O que n\u00e3o est\u00e1 adiado \u00e9 fazer o controle da entrada e sa\u00edda do Ceagesp&#8221;, disse o presidente.<\/p>\n<p>Morais disse que muitos usam a \u00e1rea do entreposto como estacionamento e ficam dias parados no local, al\u00e9m de aumentar a seguran\u00e7a contra crimes com instala\u00e7\u00e3o de c\u00e2meras. &#8220;Se encontrarmos outra forma de financiamento, poderemos (rever) a cobran\u00e7a&#8221;, disse.<\/p>\n<p>A Ceagesp planeja cadastrar os caminh\u00f5es que acessam a \u00e1rea da companhia. &#8220;A partir de 20 de mar\u00e7o, vamos proibir a entrada de ve\u00edculos que n\u00e3o t\u00eam rela\u00e7\u00e3o com o entreposto. Vamos fazer o cadastro deles&#8221;, explicou. Para o p\u00fablico, que tem outro estacionamento, n\u00e3o haver\u00e1 mudan\u00e7as.<\/p>\n<p>Homem baleado<br \/>\nO homem baleado na confus\u00e3o foi identificado como Wellington Washington dos Santos, de 23 anos. Ele foi socorrido para o Hospital Universit\u00e1rio, da Universidade de S\u00e3o Paulo (USP), tamb\u00e9m na Zona Oeste. A assessoria do hospital confirmou que ele foi submetido a uma cirurgia e estava em estado est\u00e1vel \u00e0s 17h50.<\/p>\n<p>A assessoria da Ceagesp disse, mais cedo, que os seguran\u00e7as chegaram a atirar para dispersar as pessoas que tentavam invadir um dos pr\u00e9dios administrativos. N\u00e3o est\u00e1 confirmado, por\u00e9m, como o homem foi baleado.<\/p>\n<p>Quatro pr\u00e9dios administrativos foram atacados, segundo a PM. O pr\u00e9dio do Departamento de Entrepostos (Depec), na Rua 8, foi incendiado. M\u00f3veis e equipamentos acabaram queimados. Por causa do calor do fogo, vidros se estilha\u00e7aram. Manifestantes tamb\u00e9m incendiaram ve\u00edculos e ca\u00e7ambas com madeiras.<\/p>\n<p>Segundo a Ceagesp, o entreposto tinha 70 seguran\u00e7as no momento em que a manifesta\u00e7\u00e3o se intensificou, por volta das 10h. Vinte agentes particulares estavam no pr\u00e9dio do Depec e tentaram impedir a invas\u00e3o. Neste momento, os seguran\u00e7as chegaram a atirar para tentar evitar a destrui\u00e7\u00e3o.<\/p>\n<p>Cobran\u00e7a de estacionamento<br \/>\nO tumulto na Vila Leopoldina, Zona Oeste de S\u00e3o Paulo, ocorre um dia ap\u00f3s o in\u00edcio da cobran\u00e7a de estacionamento. A Ceagesp, companhia ligada ao governo federal, fez uma licita\u00e7\u00e3o e a empresa C3V foi contratada por oito anos para &#8220;explorar o estacionamento, prover servi\u00e7os de seguran\u00e7a e organiza\u00e7\u00e3o do fluxo&#8221;.<\/p>\n<p>Ao todo, est\u00e3o previstos investimento de R$ 25 milh\u00f5es no per\u00edodo. Em contrapartida, o Entreposto vai ficar com 4% do que for arrecadado com o estacionamento.<\/p>\n<p>Nesta manh\u00e3, filas de caminh\u00f5es se formaram no entorno do maior entreposto de alimentos da Am\u00e9rica Latina. Passageiros de \u00f4nibus que passavam nas imedia\u00e7\u00f5es da Marginal Pinheiros precisaram descer dos \u00f4nibus por causa do congestionamento.<\/p>\n<p>A C3V, empresa respons\u00e1vel pela cobran\u00e7a, disse em nota que &#8220;lamenta os incidentes ocorridos esta manh\u00e3 e in\u00edcio de tarde&#8221;.<br \/>\nO Sindicato dos Permission\u00e1rios em Centrais de Abastecimento de Alimentos do Estado de S\u00e3o Paulo (Sincaesp) voltou a criticar a tarifa de estacionamento e os problemas de tr\u00e2nsito causados pelas cabines, mas negou qualquer envolvimento com o tumulto.<\/p>\n<p>\u201cOs transtornos no tr\u00e2nsito da regi\u00e3o do entreposto apenas confirmam o que o Sincaesp vem alertando: o projeto de altera\u00e7\u00e3o vi\u00e1ria, no qual est\u00e1 inclusa a cobran\u00e7a do ped\u00e1gio, n\u00e3o \u00e9 vi\u00e1vel e n\u00e3o comporta a demanda de movimenta\u00e7\u00e3o dentro e fora da Ceagesp\u201d, afirmou o sindicado em nota.<\/p>\n<p>Tarifa vari\u00e1vel<br \/>\nO valor da tarifa muda com o tempo de perman\u00eancia do ve\u00edculo. Os caminhoneiros pagam de acordo com a quantidade de eixos. Ve\u00edculos com dois eixos dever\u00e3o desembolsar R$ 4 por 4 horas. O valor pode chegar a at\u00e9 R$ 50, caso o caminh\u00e3o fique por mais de 10 horas no estacionamento. J\u00e1 os caminh\u00f5es com tr\u00eas a seis eixos pagam entre R$ 5 e R$ 60 (veja abaixo os valores).<\/p>\n<p>A cobran\u00e7a faz parte de um pacote de medidas anunciado em setembro de 2013 para melhorar a circula\u00e7\u00e3o dentro da Ceagesp, por onde passam 60 mil pessoas todos os dias. A empresa vencedora da licita\u00e7\u00e3o instalou 320 c\u00e2meras de monitoramento e novas placas de sinaliza\u00e7\u00e3o.<\/p>\n<p><strong>Tabela de pre\u00e7os<\/strong><br \/>\nConfira abaixo a rela\u00e7\u00e3o de tarifas cobradas pela concession\u00e1ria:<\/p>\n<p><strong>MOTOCICLETAS<\/strong><br \/>\nDi\u00e1ria R$ 2<br \/>\n<strong>CARROS<\/strong><br \/>\nAt\u00e9 1 hora R$ 4<br \/>\nDe 1 a 2 horas R$ 9<br \/>\nDe 1 a 3 horas R$ 11<br \/>\nDe 3 a 4 horas R$ 13<br \/>\nDe 4 a 8 horas R$ 16<br \/>\nDe 8 a 10 horas R$ 20<br \/>\nAcima de 10 horas R$ 50<br \/>\n<strong>CAMINH\u00d5ES DE 2 EIXOS<\/strong><br \/>\nAt\u00e9 4 horas R$ 4<br \/>\nDe 4 a 6 horas R$ 6<br \/>\nDe 6 a 8 horas R$ 8<br \/>\nDe 8 a 10 horas R$ 10<br \/>\nAcima de 10 horas R$ 50<\/p>\n<p><strong>CAMINH\u00d5ES DE 3 a 6 EIXOS<\/strong><br \/>\nAt\u00e9 4 horas R$ 5<br \/>\nDe 4 a 6 horas R$ 7<br \/>\nDe 6 a 8 horas R$ 9<br \/>\nDe 8 a 10 horas R$ 11<br \/>\nAcima de 10 horas R$ 60<\/p>\n<p><strong>VAREJ\u00c3O S\u00c1BADO\/DOMINGO<\/strong><br \/>\nDi\u00e1ria R$ 4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presidente do entreposto diz que vai adiar estacionamento pago. Manifesta\u00e7\u00e3o contra cobran\u00e7a de estacionamento acabou em tumulto. A Companhia de<\/p>\n","protected":false},"author":4,"featured_media":12342,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[1939,1940,47,449,361],"class_list":["post-12341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-ceagesp","tag-confrontos","tag-destaques","tag-manifestacao","tag-sao-paulo"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/12341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=12341"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/12341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/12342"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=12341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=12341"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=12341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}