{"id":15159,"date":"2014-05-06T08:46:51","date_gmt":"2014-05-06T11:46:51","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=15159"},"modified":"2014-05-06T08:46:51","modified_gmt":"2014-05-06T11:46:51","slug":"operacao-apreende-quase-3-toneladas-de-maconha-no-sertao","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/operacao-apreende-quase-3-toneladas-de-maconha-no-sertao\/","title":{"rendered":"Opera\u00e7\u00e3o apreende quase 3 toneladas de maconha no Sert\u00e3o"},"content":{"rendered":"<p><em><strong>Droga estava em tr\u00eas munic\u00edpios do Sert\u00e3o de Pernambuco.<\/strong><\/em><br \/>\n<em><strong>Trabalho foi entre as Pol\u00edcias Federal, Militar e Corpo de Bombeiros.<\/strong><\/em><\/p>\n<p>Quase tr\u00eas toneladas de maconha pronta para consumo foram erradicadas na Opera\u00e7\u00e3o &#8216;Angico I&#8217; desenvolvida pelas Pol\u00edcias Federal, Militar e o Corpo de Bombeiros em tr\u00eas munic\u00edpios do Sert\u00e3o de Pernambuco Santa Maria da Boa Vista, Cabrob\u00f3 e Oroc\u00f3.<\/p>\n<p>Esta foi a maior apreens\u00e3o da droga pronta desde o ano de 1996, segundo a Pol\u00edcia Federal.<\/p>\n<p>Cerca de 50 policiais federais e 10 policiais militares e do Corpo de Bombeiros participaram da opera\u00e7\u00e3o. O trabalho de localiza\u00e7\u00e3o do plantio foi feito via terrestre, a\u00e9rea e fluvial. A droga estava em seu per\u00edodo de colheita e a opera\u00e7\u00e3o inviabilizou a comercializa\u00e7\u00e3o da maconha para todo o Nordeste.<\/p>\n<p>A Opera\u00e7\u00e3o &#8216;Angico I&#8217; durou sete dias. De acordo com a Pol\u00edcia Federal, as opera\u00e7\u00f5es de erradica\u00e7\u00e3o do plantio de maconha na regi\u00e3o t\u00eam levado os traficantes a importar a droga de outro do Paraguai, o que tamb\u00e9m facilita a apreens\u00e3o do entorpecente vindo do pa\u00eds vizinho.<\/p>\n<p>No balan\u00e7o da Opera\u00e7\u00e3o &#8216;Angico I&#8217;, al\u00e9m da apreens\u00e3o de 2,786kg de maconha pronta para o consumo, 377 mil p\u00e9s da droga foram erradicados e 98 plantios foram destru\u00eddos. Em 2013, durante as Opera\u00e7\u00f5es Resgate I e II e Gavi\u00e3o foram apreendidas 640Kg da droga pronta para consumo.<\/p>\n<p>O nome da opera\u00e7\u00e3o &#8216;Angico I&#8217; \u00e9 por causa da vegeta\u00e7\u00e3o nativa local. Toda a droga apreendida por incinerada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Droga estava em tr\u00eas munic\u00edpios do Sert\u00e3o de Pernambuco. Trabalho foi entre as Pol\u00edcias Federal, Militar e Corpo de Bombeiros.<\/p>\n","protected":false},"author":4,"featured_media":15160,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[2173,2174,2175],"class_list":["post-15159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-cabrobo","tag-oroco","tag-santa-maria-da-boa-vista"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/15159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=15159"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/15159\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/15160"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=15159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=15159"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=15159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}