{"id":15211,"date":"2014-05-07T08:38:59","date_gmt":"2014-05-07T11:38:59","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=15211"},"modified":"2014-05-07T08:38:59","modified_gmt":"2014-05-07T11:38:59","slug":"sonho-de-ir-do-saara-a-europa-termina-em-prostituicao-e-tortura","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/sonho-de-ir-do-saara-a-europa-termina-em-prostituicao-e-tortura\/","title":{"rendered":"Sonho de ir do Saara \u00e0 Europa termina em prostitui\u00e7\u00e3o e tortura"},"content":{"rendered":"<p>Imigrantes africanos em cidade no N\u00edger falam \u00e0 BBC sobre os perigos e desencantos da maior viagem de suas vidas.<\/p>\n<p>Milhares de imigrantes africanos tentam todos os anos atravessar o continente rumo \u00e0 Europa. Muitas das jornadas passam por Agadez, no N\u00edger, ao sul do Saara, de onde come\u00e7a a passagem do deserto.<\/p>\n<p>A rota que eles tomam \u00e9 rumo \u00e0 L\u00edbia, para de l\u00e1 atravessar o Mediterr\u00e2neo. Homens que conhecem bem a regi\u00e3o cobram US$ 500 para levar pessoas at\u00e9 a L\u00edbia. Mas tamb\u00e9m \u00e9 preciso ter outros US$ 300 para pagar todas as propinas no caminho. Assista.<\/p>\n<p>Ao chegar em Agadez, no N\u00edger, muitas pessoas est\u00e3o cheias de sonhos. Mas a vida na cidade \u00e0s vezes parece um pesadelo.<\/p>\n<p>Imigrantes contaram \u00e0 BBC sobre suas experi\u00eancias. Uma mulher vinda da Nig\u00e9ria disse que seu sonho era virar enfermeira na Europa. Acabou se tornando prostituta em Agadez. Outros falam em torturas, pris\u00f5es e deporta\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imigrantes africanos em cidade no N\u00edger falam \u00e0 BBC sobre os perigos e desencantos da maior viagem de suas vidas.<\/p>\n","protected":false},"author":4,"featured_media":15212,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[47,2189],"class_list":["post-15211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-destaques","tag-nigeria"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/15211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=15211"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/15211\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/15212"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=15211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=15211"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=15211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}