{"id":20732,"date":"2014-10-06T07:53:30","date_gmt":"2014-10-06T10:53:30","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=20732"},"modified":"2017-12-29T10:15:26","modified_gmt":"2017-12-29T13:15:26","slug":"eleicoes-2014-veja-resultado-de-outros-estados","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/eleicoes-2014-veja-resultado-de-outros-estados\/","title":{"rendered":"Elei\u00e7\u00f5es 2014 \/\/ Veja resultado de outros Estados"},"content":{"rendered":"<ul>\n<li>RJ: Pez\u00e3o (PMDB) e Crivella (PRB) disputam 2\u00ba turno<\/li>\n<li>SP: Geraldo Alckmin, do PSDB,\u00a0\u00e9 reeleito governador<\/li>\n<li>PE: Paulo C\u00e2mara, do PSB,\u00a0\u00e9 eleito no 1\u00ba turno<\/li>\n<li>DF: Rollemberg (PSB) e\u00a0Frejat (PR) v\u00e3o ao 2\u00ba turno<\/li>\n<li>AC: Ti\u00e3o Viana e Marcio\u00a0Bittar disputam 2\u00ba turno<\/li>\n<li>AL: Renan Filho (PMDB)\u00a0\u00e9 eleito governador<\/li>\n<li>AP: Waldez (PDT) e Camilo (PSB) v\u00e3o disputar o 2\u00ba turno<\/li>\n<li>AM: Jos\u00e9 Melo e Eduardo\u00a0Braga enfrentam 2\u00ba turno<\/li>\n<li>BA: Rui Costa, do PT,\u00a0\u00e9 eleito governador<\/li>\n<li>MG: Fernando Pimentel (PT)\u00a0\u00e9 eleito governador<\/li>\n<li>CE: Camilo Santana e Eun\u00edcio Oliveira disputam 2\u00ba turno<\/li>\n<li>ES: Paulo Hartung (PMDB) \u00e9 eleito governador com 53%<\/li>\n<li>GO: Marconi Perillo e Iris Rezende disputam 2\u00ba turno<\/li>\n<li>MA: Fl\u00e1vio Dino, do PCdoB,\u00e9 eleito governador<\/li>\n<li>MT: Pedro Taques, do PDT,\u00a0\u00e9 eleito governador<\/li>\n<li>MS: Delc\u00eddio e Reinaldo\u00a0v\u00e3o ao 2\u00ba turno<\/li>\n<li>PA: Barbalho (PMDB) e Jatene (PSDB) v\u00e3o ao 2\u00ba turno<\/li>\n<li>PB: Cunha Lima (PSDB) e Coutinho (PSB) v\u00e3o ao 2\u00ba turno<\/li>\n<li>PR: Beto Richa, do PSDB,\u00a0\u00e9 reeleito governador<\/li>\n<li>PI: Wellington Dias (PT)\u00a0\u00e9 eleito governador<\/li>\n<li>RN: 2\u00ba turno ter\u00e1 Henrique (PMDB) e Robinson (PSB)<\/li>\n<li>RS: Sartori e Tarso Genro v\u00e3o disputar o 2\u00ba turno<\/li>\n<li>RO: Conf\u00facio e Expedito\u00a0v\u00e3o disputar 2\u00ba turno]<\/li>\n<li>RR: Suely e Chico Rodrigues v\u00e3o ao 2\u00ba turno<\/li>\n<li>SC: Raimundo Colombo\u00a0\u00e9 reeleito no 1\u00ba turno<\/li>\n<li>SE: Barreto (PMDB) \u00e9 reeleito com 53% dos votos<\/li>\n<li>TO: Marcelo Miranda (PMDB)\u00a0\u00e9 eleito governador com 51%<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>RJ: Pez\u00e3o (PMDB) e Crivella (PRB) disputam 2\u00ba turno SP: Geraldo Alckmin, do PSDB,\u00a0\u00e9 reeleito governador PE: Paulo C\u00e2mara, do<\/p>\n","protected":false},"author":4,"featured_media":18957,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[4753],"class_list":["post-20732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-eleicoes-2014"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/20732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=20732"}],"version-history":[{"count":1,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/20732\/revisions"}],"predecessor-version":[{"id":67538,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/20732\/revisions\/67538"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/18957"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=20732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=20732"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=20732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}