{"id":21149,"date":"2014-10-15T07:38:22","date_gmt":"2014-10-15T10:38:22","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=21149"},"modified":"2014-10-15T07:38:22","modified_gmt":"2014-10-15T10:38:22","slug":"em-carnaiba-mais-de-5-milhoes-de-reais-em-obras","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/em-carnaiba-mais-de-5-milhoes-de-reais-em-obras\/","title":{"rendered":"Em Carna\u00edba, mais de 5 milh\u00f5es de reais em obras"},"content":{"rendered":"<p>Mesmo enfrentando um momento de dificuldade financeira vivida pelos munic\u00edpios brasileiros a prefeitura de Carna\u00edba est\u00e1 dando sequ\u00eancia a constru\u00e7\u00e3o de v\u00e1rias obras, onde est\u00e3o sendo investidos mais de 5 milh\u00f5es de reais. Nas escolas de Ibitiranga, Serra Branca e Lagoa do Caro\u00e1 est\u00e3o sendo aplicados 3 milh\u00f5es de reais, com mais 1,2 milh\u00e3o nas Unidades B\u00e1sicas de Sa\u00fade da Fam\u00edlia em Lagoa do Caro\u00e1, Ibitiranga e na sede e ainda 905 mil reais na constru\u00e7\u00e3o de po\u00e7os, cal\u00e7amentos, pontes e bueiros. O Prefeito Z\u00e9 M\u00e1rio disse que todas estas a\u00e7\u00f5es est\u00e3o acontecendo em Carna\u00edba por que o governo tem feito um esfor\u00e7o enorme para buscar recursos e revert\u00ea-los em obras que ajudam no desenvolvimento do munic\u00edpio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mesmo enfrentando um momento de dificuldade financeira vivida pelos munic\u00edpios brasileiros a prefeitura de Carna\u00edba est\u00e1 dando sequ\u00eancia a constru\u00e7\u00e3o<\/p>\n","protected":false},"author":4,"featured_media":5619,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[50,47],"class_list":["post-21149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-carnaiba","tag-destaques"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/21149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=21149"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/21149\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/5619"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=21149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=21149"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=21149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}