{"id":21167,"date":"2014-10-15T07:54:33","date_gmt":"2014-10-15T10:54:33","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=21167"},"modified":"2014-10-15T07:54:33","modified_gmt":"2014-10-15T10:54:33","slug":"sao-paulo-joga-por-um-empate-no-chile-para-eliminar-o-huachipato","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/sao-paulo-joga-por-um-empate-no-chile-para-eliminar-o-huachipato\/","title":{"rendered":"S\u00e3o Paulo joga por um empate no Chile para eliminar o Huachipato"},"content":{"rendered":"<p style=\"text-align: justify\">Qualquer empate basta ao S\u00e3o Paulo, na noite desta quarta-feira, para eliminar o Huachipato e avan\u00e7ar \u00e0s quartas de final da Copa Sul-americana. Pela vit\u00f3ria por 1 a 0 no primeiro jogo, \u00e9 poss\u00edvel se classificar at\u00e9 mesmo com uma derrota por um gol de diferen\u00e7a, desde que o advers\u00e1rio tamb\u00e9m seja vazado. O cen\u00e1rio fica ainda melhor se levado em conta o retrospecto do time brasileiro de nunca ter sido eliminado por chilenos.<\/p>\n<p style=\"text-align: justify\">&#8220;Vamos ver o que acontece. Futebol est\u00e1 imprevis\u00edvel&#8221;, minimiza o goleiro e capit\u00e3o Rog\u00e9rio Ceni, que v\u00ea no torneio a principal chance de ser campe\u00e3o antes de se aposentar no fim da temporada, aos 41 anos. Na outra ponta da equipe, o centroavante Alan Kardec tamb\u00e9m n\u00e3o se apoia na possibilidade de empatar.<\/p>\n<p style=\"text-align: justify\">&#8220;Nosso objetivo \u00e9 fazer mais gols para aumentar nossa vantagem. Se ficarmos sentados em cima da vantagem, isso pode acabar nos prejudicando&#8221;, entende.<\/p>\n<p style=\"text-align: justify\">Entre Ceni e Kardec, Muricy Ramalho segue com desfalques. Apesar de voltar a contar com o lateral esquerdo uruguaio \u00c1lvaro Pereira, o zagueiro Paulo Miranda e o meia Paulo Henrique Ganso, o treinador s\u00e3o-paulino n\u00e3o ter\u00e1 o zagueiro Rafael Toloi, o volante Souza, os meias Maicon (que entrou na lista de baixas de \u00faltima hora, por conta de dores nas costas) e Kak\u00e1 e os atacantes Ademilson e Luis Fabiano, fora Rodrigo Caio, que s\u00f3 volta em 2015.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qualquer empate basta ao S\u00e3o Paulo, na noite desta quarta-feira, para eliminar o Huachipato e avan\u00e7ar \u00e0s quartas de final<\/p>\n","protected":false},"author":4,"featured_media":21168,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[47,2518,2569],"class_list":["post-21167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-destaques","tag-empate","tag-suficiente"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/21167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=21167"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/21167\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/21168"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=21167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=21167"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=21167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}