{"id":21173,"date":"2014-10-15T13:52:14","date_gmt":"2014-10-15T16:52:14","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=21173"},"modified":"2014-10-15T13:52:14","modified_gmt":"2014-10-15T16:52:14","slug":"prefeitura-de-afogados-promove-torneiro-aberto-de-futsal","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/prefeitura-de-afogados-promove-torneiro-aberto-de-futsal\/","title":{"rendered":"Prefeitura de Afogados promove torneiro aberto de futsal"},"content":{"rendered":"<p>A Prefeitura de Afogados da Ingazeira promove a partir da pr\u00f3xima quinta (16), o 4\u00ba Campeonato Afogadense aberto de Futebol de Sal\u00e3o. Nove equipes est\u00e3o inscritas para participar do torneio, concorrendo a premia\u00e7\u00f5es em dinheiro, trof\u00e9us e medalhas.<\/p>\n<p>Participam as equipes do CNA, Rancho Fundo, Combinado Sobreira, For\u00e7a Jovem, Mercantil Tavares F.C., Academia Vida Ativa F.C, S\u00e3o Borges, Real Sobreira e Gr\u00eamio da Alagoinha. A cerim\u00f4nia de abertura ocorre nesta quinta, a partir das 18 horas, no Centro Desportivo L\u00facio Luiz de Almeida.<\/p>\n<p>A rodada de abertura ter\u00e1 os seguintes jogos: Rancho Fundo x Real Sobreira (19h) e CNA x Academia Vida Ativa (20h).<\/p>\n<p>Os jogos do campeonato acontecer\u00e3o todas as quintas e sextas sempre \u00e0s 19 horas, at\u00e9 o dia 14 de Novembro, quando ocorrer\u00e3o as finais do torneio.<\/p>\n<p><em>\u201cJ\u00e1 realizamos torneios de handebol, xadrez, basquete, j\u00e1 apoiamos os times de afogados na Copa do Interior e na S\u00e9rie A2, e estamos promovendo a inclus\u00e3o de crian\u00e7as e adolescentes atrav\u00e9s do Programa Esporte nos Bairros. Esse torneio \u00e9 mais uma iniciativa importante no \u00e2mbito da pol\u00edtica municipal de valoriza\u00e7\u00e3o do esporte amador,\u201d<\/em> afirmou o Secret\u00e1rio Municipal de Cultura e Esportes, Alessandro Palmeira.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Afogados da Ingazeira promove a partir da pr\u00f3xima quinta (16), o 4\u00ba Campeonato Afogadense aberto de Futebol<\/p>\n","protected":false},"author":4,"featured_media":21174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[15,47,2081],"class_list":["post-21173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-afogados-da-ingazeira","tag-destaques","tag-futsal"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/21173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=21173"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/21173\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/21174"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=21173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=21173"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=21173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}