{"id":22875,"date":"2014-11-24T07:51:29","date_gmt":"2014-11-24T10:51:29","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=22875"},"modified":"2014-11-24T07:51:29","modified_gmt":"2014-11-24T10:51:29","slug":"final-de-semana-com-muitas-ocorrencias-na-area-do-23o-bpm-2","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/final-de-semana-com-muitas-ocorrencias-na-area-do-23o-bpm-2\/","title":{"rendered":"Final de semana com muitas ocorr\u00eancias na \u00e1rea do 23\u00ba BPM"},"content":{"rendered":"<h2><strong>Tentativa de homic\u00eddio em Itapetim<\/strong><\/h2>\n<p>A GT recebeu liga\u00e7\u00e3o telef\u00f4nica do hospital de Itapetim informando que tinha dado entrada uma v\u00edtima de disparos de arma de fogo. No hospital testemunhas informaram que a v\u00edtima Jailson Alves de Lima, Solteiro, 26 anos, morador do Centro de Itapetim, se encontrava no Distrito de Piedade, sentada em uma moto conversando com alguns conhecidos, momento em que o acusado, que \u00e9 conhecido por \u201cZ\u00e9 de Magra\u201d, se aproximou por tr\u00e1s e efetuou cerca de cinco a seis disparos de arma de fogo, supostamente de rev\u00f3lver, nas costas da v\u00edtima, a qual foi socorrida em estado grave ao hospital de Itapetim e posteriormente encaminhada ao Hospital da cidade de Patos-PB. A ocorr\u00eancia foi repassada a DP.<\/p>\n<h2><strong>Siena sobra na curva e mata motorista em S\u00e3o Jose do Egito<\/strong><\/h2>\n<p>O acidente aconteceu na PE 320 Riacho do meio, S\u00e3o Jose do Egito envolvendo um FIAT SIENA ELX, cor prata ano 2009 de placa EDL-6215, SP. O policiamento ao chegar ao local se deparou com a v\u00edtima Paulo Jose da Silva, 55 anos, solteiro, ocupa\u00e7\u00e3o n\u00e3o informada, natural de Diadema SP, ca\u00edda ao lado do ve\u00edculo. A ambul\u00e2ncia foi solicitada e a v\u00edtima conduzida para o hospital local, porem ap\u00f3s os primeiros socorros veio a \u00f3bito. A ocorr\u00eancia foi repassada para aquela de para que sejam tomadas as devidas provid\u00eancias. No celular havia uma mensagem passada no momento do acidente, onde dizia \u201dt\u00f4 chegando\u201d. Paulo residia em Diadema, mas visitava os parentes em Racho do Meio onde estava a alguns dias.<\/p>\n<h2><strong>Homem flagrado com maconha em Afogados<\/strong><\/h2>\n<p>Durante abordagem no\u00a0Bar da Separa\u00e7\u00e3o,\u00a0Bairro Borges, a pol\u00edcia encontrou\u00a0tr\u00eas gramas de maconha que estavam\u00a0com o acusado Ant\u00f4nio Ricardo Siqueira de Farias, 25 anos, Carapuceiro, morador Residencial Laura Ramos. O\u00a0mesmo foi encaminhado a DP.\u00a0<strong>\u00a0<\/strong><\/p>\n<h2><strong>Em Afogados, v\u00e2ndalos jogam pedras na cobertura do Centro Desportivo<\/strong><\/h2>\n<p>A Rocam foi acionada \u00e1\u00a0Rua Ant\u00f4nio Vidal, centro, Afogados da Ingazeira, onde a guarda municipal havia apreendido o menor M. R. de S., 17 anos, solteiro, estudante, o qual estava na companhia de outros indiv\u00edduos n\u00e3o identificados, jogando pedras na cobertura do Gin\u00e1sio Desportivo. Segundo a v\u00edtima\u00a0Jos\u00e9 Carlos da Silva, 46 anos, casado, Guarda Municipal, o menor o desacatou no exerc\u00edcio de sua fun\u00e7\u00e3o usando palavras de baixo cal\u00e3o. A ocorr\u00eancia foi repassada a DP.<strong>\u00a0<\/strong><\/p>\n<h2><strong>Ajudante autuado na Lei Maria da Penha em S\u00e3o Jos\u00e9 do Egito<\/strong><\/h2>\n<p>A GT foi acionada \u00e0 Rua Beco da Celpe, no centro de S\u00e3o Jose do Egito, onde a vitima Emanoela Soares Mendes, 22 anos, domestica, informou que foi agredida\u00a0com socos, tapas e ponta p\u00e9s\u00a0pelo companheiro Sidney Ferreira da Silva, 25 anos, amasiado, ajudante geral. Para se proteger das agress\u00f5es, a mesma correu para a casa da vizinha Marcela Roberta Paula de Oliveira, 35 anos, casada, domestica, por\u00e9m o acusado\u00a0invadiu a resid\u00eancia e continuou a agredi-la. As partes foram encaminhadas a DP de plant\u00e3o em Afogados da Ingazeira-PE, onde o acusado foi autuado em flagrante delito, por ter infringido a Lei Maria da Penha.<\/p>\n<h2><strong>Agricultores s\u00e3o presos com armas de fogo em S\u00e3o Jos\u00e9 do Egito<\/strong><\/h2>\n<p>A GT foi informada atrav\u00e9s de denuncia an\u00f4nima que no S\u00edtio Ponta Direita, zona rural de S\u00e3o Jos\u00e9 do Egito, os acusados Valdecir Cardoso dos Santos, 52 anos, solteiro, agricultor e Rodrigo Jos\u00e9 dos Santos Lima, 30 anos, casado, agricultor estavam de posse de v\u00e1rias armas de fogo. O policiamento foi at\u00e9 as resid\u00eancias dos envolvidos, sendo que Valdecir entregou espontaneamente uma espingarda CBC, calibre 36, n\u00ba 273X3, bem como, 31 (trinta e um) cartuchos de mesmo calibre, sendo: 10 (dez) intactos e 21 (vinte e um) deflagrados, enquanto Rodrigo entregou\u00a001 (uma) espingarda anticarga (soca-soca). Os dois envolvidos foram conduzidos a DP de Afogados da Ingazeira e autuados em flagrante por porte ilegal de arma de fogo.<\/p>\n<h2><strong>Em Tabira, agricultor amea\u00e7a o irm\u00e3o com uma faca por causa de uma estaca de cerca<\/strong><\/h2>\n<p>A GT foi acionada ao Parque de Vaquejada do S\u00edtio Comich\u00e3o, em Tabira, pela vitima Valdeir In\u00e1cio Nogueira, 38 anos, solteiro, vigilante, o qual informou que estava com seu pai fazendo uma cerca de arame, quando o acusado Valdir da Silva Nogueira, 25 anos, casado, agricultor, que \u00e9 seu irm\u00e3o, aproximou-se deles e come\u00e7ou quebrar tudo, porque tinham utilizado uma estaca que era dele. Armado com uma faca peixeira o acusado ainda amea\u00e7ou matar o irm\u00e3o, e depois evadiu-se do local. A pol\u00edcia fez dilig\u00eancias, mas n\u00e3o conseguiu localiz\u00e1-lo.<\/p>\n<h2><strong>Desocupado \u00e9 detido guiando moto embriagado no Sobreira<\/strong><\/h2>\n<p>A GT ao realizar Blitz Bloqueio na\u00a0Rua Nelson Alves de Souza, Sobreira,\u00a0se deparou com o imputado\u00a0Miguel \u00c2ngelo Beserra Lino, 24 anos, solteiro, desocupado, morador do S\u00edtio po\u00e7o de Pedra\u00a0conduzindo uma moto HONDA NXR 150, cor preta, e apresentava vis\u00edveis sinais de embriaguez alco\u00f3lica, com os olhos vermelhos, h\u00e1lito com forte odor et\u00edlico e fala desconexa. Ao realizar o teste com o etil\u00f4metro, obteve o resultado 1,09 mg\/l. Diante dos fatos o imputado foi conduzido a DP local, onde foi autuado em flagrante delito, e o ve\u00edculo foi recolhido a 24\u00aa CIRETRAN, por n\u00e3o ter sido apresentado o documento de porte obrigat\u00f3rio.<\/p>\n<h2><strong>Homem agride porteiro e quebra vidro de hospital em Tuparetama<\/strong><\/h2>\n<p>A GT foi acionada ao Hospital Municipal de Tuparetama, onde o porteiro da reparti\u00e7\u00e3o Lourival Francisco de Oliveira, 63 anos, informou que o acusado Elizaudo dos Santos Bezerra,18 anos, solteiro, agricultor havia lhe agredido e quebrado uma janela de vidro da unidade. Como se feriu com os estilha\u00e7os, o acusado recebeu atendimento m\u00e9dico e em seguida foi encaminhado a DP.<\/p>\n<h2><strong>Mulher \u00e9 agredida pelo companheiro em S\u00e3o Jos\u00e9 do Egito<\/strong><\/h2>\n<p>A vitima Irani de Lima Oliveira Nascimento, 32 anos, amasiada, do lar, moradora da Rua Virginia Rocha, S\u00e3o Borja, procurou a pol\u00edcia informando que estava trabalhando em uma resid\u00eancia quando o seu companheiro Dalvan dos Santos Silva, 26 anos, amasiado, desocupado chegou embriagado e desferiu socos na mesma. A v\u00edtima procurou o hospital onde foi submetida a exame traumatol\u00f3gico, e logo ap\u00f3s procurou a policia militar. O efetivo foi at\u00e9 o Sitio Timbauba, zona rural daquele munic\u00edpio na tentativa de localizar o acusado, por\u00e9m sem \u00eaxito.<\/p>\n<h2><strong>Pol\u00edcia encontra celular que seria entregue a preso na Cadeia de Afogados<\/strong><\/h2>\n<p>A guarda da Cadeia de Afogados da Ingazeira recebia as refei\u00e7\u00f5es para os detentos, quando um individuo n\u00e3o identificado entregou uma\u00a0caixa de margarina e uma sacola de p\u00e3es, para serem entregues ao detento\u00a0Klebson Jos\u00e9 da Silva,\u00a0que encontra-se recolhido na cela 06, por\u00e9m durante a revista de rotina, foi encontrado um aparelho celular de marca NOKIA na cor preta, sem chip, que estava junto com a comida. As guarni\u00e7\u00f5es foram acionadas na tentativa de localizar o entregador desconhecido por meio de suas caracter\u00edsticas exibidas pela as c\u00e2maras de seguran\u00e7a, mas sem \u00eaxito.<\/p>\n<h2><strong>Em Iguaracy, vidro da porta do Banco do Brasil se estilha\u00e7a e deixa uma pessoa ferida<\/strong><\/h2>\n<p>A vitima Dathanne Almeida Coelho, 35 anos, solteira, advogada, informou a pol\u00edcia que ao abrir a porta frontal do Banco do Brasil daquela cidade o vidro da porta se estilha\u00e7ou, causando les\u00f5es leves em seu bra\u00e7o direito. A v\u00edtima foi conduzida ao Hospital Municipal para atendimento m\u00e9dico e em seguida encaminhada a DP.<\/p>\n<h2><strong>Homem agredido por tr\u00eas indiv\u00edduos no est\u00e1dio de Tuparetama<\/strong><\/h2>\n<p>A vitima Dami\u00e3o Jose Cabral, 30 anos, solteiro, agricultor, morador do Bom Jesus, procurou a GT informando ter sido agredido pelos tr\u00eas acusados Pedro Luiz S. Barbosa; Jose Ridaildo Leite e Jos\u00e9 Leonardo, durante um jogo no est\u00e1dio Lucena Chalega. O efetivo fez rondas, mas n\u00e3o localizou os acusados.<\/p>\n<h2><strong>Dupla tenta roubar moto em Tuparetama<\/strong><\/h2>\n<p>A vitima Levino Gomes dos Santos, 58 anos, agricultor procurou a pol\u00edcia informando que os acusados Ronieri Barbosa dos Santos, 25 anos, solteiro, repositor e R. V. da S. A., 16 anos, solteiro, haviam tentado roubar sua motocicleta Honda CG 125, cor azul, ano 2003, placa OGM 8207, na Rua Ant\u00f4nio Gomes, Centro, Tuparetama, e n\u00e3o obtendo \u00eaxito, fugiram. A GT fez diligencias e conseguiu localizar e deter o acusado Ronieri Barbosa,\u00a0 que estava em sua resid\u00eancia, na Rua Delmiro Matias, n\u00ba 50. O menor n\u00e3o foi encontrado.<\/p>\n<h2><strong>Pol\u00edcia flagra menores ingerindo bebida alc\u00f3olica em bar de S\u00e3o Jos\u00e9 do Egito<\/strong><\/h2>\n<p>As equipes da ROCAM, GT e GATI, ao realizarem abordagens no interior do \u201cclube do Bigode\u201d, Rua Santos Dumont, s\/n, bairro S\u00e3o Jo\u00e3o, S\u00e3o Jos\u00e9 do Egito, flagraram as adolescentes C. J. de S. S., 16 anos; K. E. L. da S., 15 anos; M. de O. S., 16 anos e P. B. R. L. de M., 14 anos, no interior do estabelecimento, sem estarem acompanhadas dos pais ou respons\u00e1veis. A menor M. de O. S., estava ingerindo bebida alco\u00f3lica, com um copo descart\u00e1vel contendo 140 ml de whisky. O acusado Francisco de Assis Paz, 59 anos, casado, comerciante, que \u00e9 propriet\u00e1rio do estabelecimento, juntamente com as adolescentes, foram conduzidos \u00e0quela DP.<\/p>\n<h2><strong>Menor \u00e9 pego conduzindo motocicleta sem placa em Tabira<\/strong><\/h2>\n<p>A GT ao realizar blitz\/bloqueio na Av. Cel Zuza Barros, centro, Tabira abordou uma motocicleta Honda POP 100, cor preta, ano 2014, sem placa, conduzida pelo menor J. E. L. de A., 16 anos, solteiro, estudante, residente na Rua Bela Vista, n\u00ba 258, Brejinho, Tabira, que disse que a moto pertencia ao seu irm\u00e3o e que que o mesmo tinha ci\u00eancia do fato. A motocicleta encontrava-se sem placa de identifica\u00e7\u00e3o, em virtude de ainda n\u00e3o ter feito o primeiro emplacamento. Diante dos fatos a ocorr\u00eancia foi passada a disposi\u00e7\u00e3o da DP local e a motocicleta foi recolhida a 24\u00aa CIRETRAN- em Afogados da Ingazeira.<\/p>\n<h2><strong>Menor flagrado empinando moto em Solid\u00e3o<\/strong><\/h2>\n<p>Durante rondas no povoado de Pelo Sinal a GT ordin\u00e1ria flagrou o menor infrator J. W. G. da S., 15 anos, solteiro, estudante conduzindo uma moto HONDA\/Pop 100, cor amarela, ano 2008, placa KLY 5978, na ocasi\u00e3o o mesmo estava\u00a0\u201cempinando\u201d\u00a0a referida motocicleta, colocando em risco sua pr\u00f3pria vida e a dos transeuntes. O adolescente foi encaminhado, juntamente com o ve\u00edculo, a DP.<\/p>\n<h2><strong>Homem \u00e9 agredido em Afogados<\/strong><\/h2>\n<p>A pol\u00edcia foi acionada \u00e0\u00a0Rua Frei Miguelino, Bairro Padre Pedro Pereira, Afogados da Ingazeira, para\u00a0verificar uma ocorr\u00eancia de agress\u00e3o. No local, a vitima\u00a0Jose Carlos Gomes Pereira, 35 anos, solteiro, agricultor\u00a0informou que um indiv\u00edduo, conhecido por &#8220;Toioba&#8221;, chegou e lhe pediu R$ 2,00, e que ap\u00f3s ter dito que n\u00e3o tinha a quantia, o acusado desferiu um soco, causando um corte na regi\u00e3o da boca. O imputado evadiu-se do local e a ocorr\u00eancia foi repassada a DP.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tentativa de homic\u00eddio em Itapetim A GT recebeu liga\u00e7\u00e3o telef\u00f4nica do hospital de Itapetim informando que tinha dado entrada uma<\/p>\n","protected":false},"author":4,"featured_media":151,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[47,4750],"class_list":["post-22875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-destaques","tag-plantao-de-policia"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/22875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=22875"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/22875\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/151"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=22875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=22875"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=22875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}