{"id":30639,"date":"2015-04-19T23:05:44","date_gmt":"2015-04-20T02:05:44","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=30639"},"modified":"2015-04-19T23:05:44","modified_gmt":"2015-04-20T02:05:44","slug":"bahia-vence-de-virada-avanca-no-estadual-e-chega-a-sua-segunda-final-em-uma-semana","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/bahia-vence-de-virada-avanca-no-estadual-e-chega-a-sua-segunda-final-em-uma-semana\/","title":{"rendered":"Bahia vence de virada, avan\u00e7a no Estadual e chega \u00e0 sua segunda final em uma semana"},"content":{"rendered":"<p style=\"text-align: justify\">Os torcedores do Bahia ainda nem haviam terminado de comemorar a vaga na final da Copa do Nordeste e, uma semana depois, j\u00e1 puderam sentir o sabor navamente. Neste domingo, o clube venceu o Juazeirense por 3 a 2 e avan\u00e7ou para a decis\u00e3o do Campeonato Baiano.<\/p>\n<p style=\"text-align: justify\">Depois de sair perdendo por 2 a 0, o clube conseguiu buscar a virada com gols de Maxi Biancucchi, Souza e Z\u00e9 Roberto. O resultado foi mais que suficiente para chegar \u00e0 final, pois o clube j\u00e1 havia vencido o jogo de ida, em Juazeiro, por 2 a 1.<\/p>\n<p style=\"text-align: justify\">Com a vit\u00f3ria, o Bahia chega ao seu 16\u00b0 jogo consecutivo sem derrotas. Jogando na Fonte Nova, o clube ainda n\u00e3o sabe o que \u00e9 perder em 2015.<\/p>\n<p style=\"text-align: justify\">O pr\u00f3ximo compromisso do Bahia ser\u00e1 contra o Cear\u00e1, nesta quarta-feira, pela final da Copa do Nordeste. O time ainda avan\u00e7ou na Copa do Brasil ap\u00f3s superar o Nacional-AM e enfrentar\u00e1 na pr\u00f3xima fase o Luverdense.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os torcedores do Bahia ainda nem haviam terminado de comemorar a vaga na final da Copa do Nordeste e, uma<\/p>\n","protected":false},"author":4,"featured_media":30640,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[1551,47,3967],"class_list":["post-30639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-bahia","tag-destaques","tag-sofrido"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/30639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=30639"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/30639\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/30640"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=30639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=30639"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=30639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}