{"id":30642,"date":"2015-04-19T23:08:39","date_gmt":"2015-04-20T02:08:39","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=30642"},"modified":"2015-04-19T23:08:39","modified_gmt":"2015-04-20T02:08:39","slug":"rogerio-paraiba-faz-dois-ofusca-diego-souza-e-sport-perde-fora-de-casa","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/rogerio-paraiba-faz-dois-ofusca-diego-souza-e-sport-perde-fora-de-casa\/","title":{"rendered":"Rog\u00e9rio Para\u00edba faz dois, ofusca Diego Souza, e Sport perde fora de casa"},"content":{"rendered":"<p style=\"text-align: justify\">Nem Durval, nem Diego Souza. O Sport n\u00e3o conseguiu chamar a responsabilidade com seus homens mais experientes em nenhum dos setores e acabou derrotado, por 2 a 0, pelo Salgueiro, no Corn\u00e9lio de Barros, neste domingo, com dois gols de Rog\u00e9rio Para\u00edba. Este foi o primeiro dos dois embates entre os times para decidir quem passa \u00e0 final do Campeonato Pernambucano. O pr\u00f3ximo jogo acontece na Arena Pernambuco.<\/p>\n<p style=\"text-align: justify\">O gol do Sport n\u00e3o saiu por um milagre. A equipe terminou os primeiros 45 minutos de jogo com 71% de posse de bola. A grande chance saiu dos p\u00e9s de Diego Souza. Aos 26 minutos, o atacante chutou de fora da \u00e1rea e assustou o goleiro advers\u00e1rio, Luciano.<\/p>\n<p style=\"text-align: justify\">Mal sabia Luciano que seria ele o respons\u00e1vel por operar milagres no segundo tempo de partida. Antes disso, por\u00e9m, Rodolfo Potiguar e Kanu tiveram chances de abrir o placar para o Salgueiro, mas n\u00e3o tiveram sucesso.<\/p>\n<p style=\"text-align: justify\">Na sequ\u00eancia, Felipe Azevedo ficou na cara do arqueiro e tinha tudo para tirar o zero do placar, mas perdeu o tempo do drible e deixou com o que o camisa 1 fechasse o \u00e2ngulo do chute. Em seguida, foi a vez de Samuel chutar. De novo, Luciano apareceu para fazer boa defesa.<\/p>\n<p style=\"text-align: justify\">Se Luciano trabalhou, Magr\u00e3o n\u00e3o ficou atr\u00e1s. No entanto, o goleiro do Sport n\u00e3o teve a sorte de seu colega de posi\u00e7\u00e3o. Aos 30 minutos, C\u00e1ssio chutou e Durval desviou com as m\u00e3os dentro da \u00e1rea. P\u00eanalti para o Salgueiro.<\/p>\n<p style=\"text-align: justify\">Na cobran\u00e7a, Magr\u00e3o at\u00e9 pulou para o canto certo, mas n\u00e3o o suficiente para evitar o gol de Rog\u00e9rio Para\u00edba. Alguns minutos depois, Kanu foi derrubado por Rithely e, novamente, o juiz marcou p\u00eanalti para o Salgueiro.<\/p>\n<p style=\"text-align: justify\">Rog\u00e9rio Para\u00edba foi para a cobran\u00e7a e, dessa vez, Magr\u00e3o n\u00e3o acertou o canto e tampouco evitou o segundo gol do time da casa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nem Durval, nem Diego Souza. O Sport n\u00e3o conseguiu chamar a responsabilidade com seus homens mais experientes em nenhum dos<\/p>\n","protected":false},"author":4,"featured_media":30643,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[2719,47,198,114],"class_list":["post-30642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-atletico-x-flamengo-destaques","tag-destaques","tag-salgueiro","tag-sport"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/30642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=30642"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/30642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/30643"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=30642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=30642"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=30642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}