{"id":32862,"date":"2015-05-26T08:20:10","date_gmt":"2015-05-26T11:20:10","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=32862"},"modified":"2015-05-26T08:20:10","modified_gmt":"2015-05-26T11:20:10","slug":"desfiles-militar-e-estudantil-marcarao-aniversario-de-tabira","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/desfiles-militar-e-estudantil-marcarao-aniversario-de-tabira\/","title":{"rendered":"Desfiles militar e estudantil marcar\u00e3o anivers\u00e1rio de Tabira"},"content":{"rendered":"<p>Tabira festeja amanh\u00e3 27 de maio 66 anos de Emancipa\u00e7\u00e3o pol\u00edtica. O anivers\u00e1rio da Cidade das Tradi\u00e7\u00f5es ser\u00e1 marcado pela administra\u00e7\u00e3o Sebasti\u00e3o Dias (PTB) com dois desfiles. Pela manh\u00e3 o desfile militar e \u00e1 tarde o desfile estudantil.<\/p>\n<p>Falando a R\u00e1dio Cidade FM ontem pela manh\u00e3 o Secret\u00e1rio de Administra\u00e7\u00e3o Fl\u00e1vio Marques anunciou a programa\u00e7\u00e3o matinal que come\u00e7ar\u00e1 as 8h com o hasteamento das bandeiras e em seguida o desfile militar que apresentar\u00e1 pela ordem: a Banda do Corpo de Bombeiros do Recife; Guarda Municipal de Tabira, Afogados da Ingazeira e Serra Talhada; Banda de M\u00fasica do Ex\u00e9rcito vinda de Garanhuns; Tiro de Guerra de Afogados da Ingazeira; Grupo dos Desbravadores; Banda da Policia Militar do Recife; Pelot\u00f5es do Gati, Rocam, Policia Militar, Policia Civil, Patrulha Mirim, alunos do Proerd, e viaturas da Ciosac, Policia Rodovi\u00e1ria Federal e Corpo de Bombeiros.<\/p>\n<p>De acordo com Fl\u00e1vio Marques s\u00e3o 349 homens que desfilar\u00e3o na festa de anivers\u00e1rio de Tabira. A tarde haver\u00e1 o desfile estudantil. A noite, de acordo com o Secret\u00e1rio, diante das dificuldades financeiras, n\u00e3o haver\u00e1 apresenta\u00e7\u00e3o de show musical.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tabira festeja amanh\u00e3 27 de maio 66 anos de Emancipa\u00e7\u00e3o pol\u00edtica. O anivers\u00e1rio da Cidade das Tradi\u00e7\u00f5es ser\u00e1 marcado pela<\/p>\n","protected":false},"author":4,"featured_media":3628,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[47,38],"class_list":["post-32862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-destaques","tag-tabira"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/32862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=32862"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/32862\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/3628"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=32862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=32862"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=32862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}