{"id":32872,"date":"2015-05-26T08:52:22","date_gmt":"2015-05-26T11:52:22","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=32872"},"modified":"2015-05-26T08:52:22","modified_gmt":"2015-05-26T11:52:22","slug":"paulo-camara-sanciona-lei-que-proibe-fumar-nos-estadios-de-futebol-em-pernambuco","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/paulo-camara-sanciona-lei-que-proibe-fumar-nos-estadios-de-futebol-em-pernambuco\/","title":{"rendered":"Paulo C\u00e2mara sanciona lei que pro\u00edbe fumar nos est\u00e1dios de futebol em Pernambuco"},"content":{"rendered":"<p>Lei n\u00ba 15.514 \u00e9 de autoria do deputado Odacy Amorim<\/p>\n<p>A partir de agora, al\u00e9m do veto \u00e0s bebidas alco\u00f3licas, est\u00e1 proibido fumar dentro dos est\u00e1dios de futebol de Pernambuco.<\/p>\n<p>O governador Paulo C\u00e2mara (PSB) sancionou a Lei n\u00ba 15.514, de autoria do deputado Odacy Amorim (PT), que veta o uso de cigarros, cigarrilhas, charutos, cachimbos ou de qualquer outro produto fum\u00edgeno, derivado ou n\u00e3o do tabaco nos est\u00e1dios de futebol em Pernambuco. A \u00fanica exce\u00e7\u00e3o \u00e9 em locais exclusivamente para esse fim, devidamente isolado e com arejamento conveniente.<\/p>\n<p>A lei, publicada no Di\u00e1rio Oficial do Estado do \u00faltimo s\u00e1bado, entrar\u00e1 em vigor em 180 dias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lei n\u00ba 15.514 \u00e9 de autoria do deputado Odacy Amorim A partir de agora, al\u00e9m do veto \u00e0s bebidas alco\u00f3licas,<\/p>\n","protected":false},"author":4,"featured_media":32873,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[47,4748],"class_list":["post-32872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-destaques","tag-pernambuco"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/32872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=32872"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/32872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/32873"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=32872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=32872"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=32872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}