{"id":37538,"date":"2015-09-03T08:08:54","date_gmt":"2015-09-03T11:08:54","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=37538"},"modified":"2015-09-03T08:08:54","modified_gmt":"2015-09-03T11:08:54","slug":"profissionais-do-creas-regional-recebem-aviso-previo-em-afogados-e-no-resto-do-estado","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/profissionais-do-creas-regional-recebem-aviso-previo-em-afogados-e-no-resto-do-estado\/","title":{"rendered":"Profissionais do CREAS Regional recebem aviso pr\u00e9vio\u00a0em Afogados e no resto do estado"},"content":{"rendered":"<p>Um baque na rede social de Afogados da Ingazeira e regi\u00e3o. Vivenciando a crise que atinge os estados, o Governo de Pernambuco anunciou o aviso pr\u00e9vio para os profissionais do CREAS Regional, existente em Afogados da Ingazeira e em mais 12 munic\u00edpios do estado.<\/p>\n<p>Assim, coordenador geral, advogado, psic\u00f3logo, assistente social e outros profissionais ser\u00e3o desligados. A perda ser\u00e1 enorme, pois o CREAS tem papel importante em servi\u00e7os como: Prote\u00e7\u00e3o e Atendimento Especializado a Fam\u00edlias e Indiv\u00edduos; Prote\u00e7\u00e3o Social a Adolescentes em Cumprimento de Medida Socioeducativa de Liberdade Assistida e de Presta\u00e7\u00e3o de Servi\u00e7os \u00e0 Comunidade; Servi\u00e7o Especializado em Abordagem Social e Prote\u00e7\u00e3o Social Especial para Pessoas com Defici\u00eancia, Idosas e suas Fam\u00edlias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um baque na rede social de Afogados da Ingazeira e regi\u00e3o. Vivenciando a crise que atinge os estados, o Governo<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[309],"class_list":["post-37538","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-creas"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/37538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=37538"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/37538\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=37538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=37538"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=37538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}