{"id":48605,"date":"2016-06-20T18:04:39","date_gmt":"2016-06-20T21:04:39","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=48605"},"modified":"2016-06-20T18:04:39","modified_gmt":"2016-06-20T21:04:39","slug":"afogados-da-ingazeira-em-entrevista-totonho-valadares-diz-nao-estar-inelegivel","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/afogados-da-ingazeira-em-entrevista-totonho-valadares-diz-nao-estar-inelegivel\/","title":{"rendered":"Afogados da Ingazeira: em entrevista Totonho Valadares diz n\u00e3o estar ineleg\u00edvel\u00a0"},"content":{"rendered":"<p>Na manh\u00e3 desta segunda-feira (20), o ex-prefeito Totonho Valadares, disse em entrevista ao comunicador Nill J\u00fanior durante o programa Manh\u00e3 Total da R\u00e1dio Paje\u00fa, que n\u00e3o procede a informa\u00e7\u00e3o de que estaria na lista dos fichas-sujas.<\/p>\n<p>H\u00e1 alguns dias foi enviada uma lista pelo TCU ao TSE contendo nomes de pol\u00edticos que est\u00e3o citados em processos. Totonho falou que o nome que consta na lista n\u00e3o significa que esteja ineleg\u00edvel e que isso vai ficar a crit\u00e9rio do Tribunal Superior Eleitoral decidir.<\/p>\n<p>O seu nome consta na lista devido a um projeto que teve in\u00edcio na gest\u00e3o da ex-prefeita Giza sobre a implanta\u00e7\u00e3o de uma esta\u00e7\u00e3o de tratamento de esgoto e que estava sendo responsabilizado por uma coisa que n\u00e3o fez.<\/p>\n<p>Totonho afirmou que dentro do projeto j\u00e1 havia algumas bacias de decanta\u00e7\u00e3o constru\u00eddas em um terreno nas proximidades do bairro S\u00e3o Crist\u00f3v\u00e3o e que por v\u00e1rias vezes foram chamados engenheiros da Caixa Econ\u00f4mica Federal para verificar o local e que demoram a realizar a visita, veio uma enxurrada e levou o que j\u00e1 tinha sido constru\u00eddo. \u201cEles est\u00e3o me responsabilizando por n\u00e3o ter conclu\u00eddo a obra, por uma coisa que n\u00e3o fiz\u201d, disse.<\/p>\n<p>Ainda sobre o caso, Totonho reafirmou o que disse em entrevista no dia 24 de dezembro de 2015, nos mesmos est\u00fadios, que foi procurado pelos filhos da ex-prefeita Giza Sim\u00f5es, Danilo e Eug\u00eania, para dividir em partes iguais o valor e que a princ\u00edpio n\u00e3o aceitou, dizendo que n\u00e3o foi o respons\u00e1vel pela situa\u00e7\u00e3o, mas que depois a pedido de seu advogado resolveu aceitar. Totonho reafirmou que os pagamentos est\u00e3o em dia e que j\u00e1 est\u00e1 se movimentando junto com os advogados para resolver o problema.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 desta segunda-feira (20), o ex-prefeito Totonho Valadares, disse em entrevista ao comunicador Nill J\u00fanior durante o programa Manh\u00e3<\/p>\n","protected":false},"author":4,"featured_media":48606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[15,47,135],"class_list":["post-48605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-afogados-da-ingazeira","tag-destaques","tag-totonho-valadares"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/48605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=48605"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/48605\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/48606"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=48605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=48605"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=48605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}