{"id":51514,"date":"2016-10-04T08:40:00","date_gmt":"2016-10-04T11:40:00","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=51514"},"modified":"2016-10-04T08:40:00","modified_gmt":"2016-10-04T11:40:00","slug":"imagem-peregrina-chega-nesta-terca-na-paroquia-do-senhor-bom-jesus-dos-remedios","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/imagem-peregrina-chega-nesta-terca-na-paroquia-do-senhor-bom-jesus-dos-remedios\/","title":{"rendered":"Imagem Peregrina chega nesta ter\u00e7a na Par\u00f3quia do Senhor Bom Jesus dos Rem\u00e9dios"},"content":{"rendered":"<p><em>Do Afogados On-Line<\/em><\/p>\n<p>Depois de passar cinco meses peregrinando em 23 par\u00f3quias da diocese de Afogados da Ingazeira finalmente a Imagem Peregrina de Nossa Senhora Aparecida chega \u00e0 Par\u00f3quia do Senhor Bom Jesus dos Rem\u00e9dios nesta ter\u00e7a (4). A Imagem se encontra na Par\u00f3quia de Santo Ant\u00f4nio e S\u00e3o Jo\u00e3o Maria Vianey, em Carna\u00edba.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-51515 alignleft\" src=\"http:\/\/www.radiopajeu.com.br\/portal\/wp-content\/uploads\/2016\/10\/programacao-santa.png\" alt=\"programacao-santa\" width=\"399\" height=\"279\" srcset=\"http:\/\/www.radiopajeu.com.br\/portal\/wp-content\/uploads\/2016\/10\/programacao-santa.png 458w, http:\/\/www.radiopajeu.com.br\/portal\/wp-content\/uploads\/2016\/10\/programacao-santa-300x210.png 300w\" sizes=\"auto, (max-width: 399px) 100vw, 399px\" \/>A chegada da Santa est\u00e1 prevista para as 19h na Capela de S\u00e3o Sebasti\u00e3o em Afogados. Depois, segue em prociss\u00e3o at\u00e9 a Catedral onde acontecer\u00e1, \u00e0s 20h, a Missa de Acolhida que ter\u00e1 transmiss\u00e3o da R\u00e1dio Paje\u00fa.<\/p>\n<p>Uma grande concentra\u00e7\u00e3o de motociclistas e mototaxistas est\u00e1 programa para acontecer um pouco antes das 19h nas proximidades do trevo da Ponte para aguardar a chegada da Imagem e seguir em passeata at\u00e9 a Capela de S\u00e3o Sebasti\u00e3o.<\/p>\n<p>Diferente do que aconteceu em outras dioceses, a Imagem que est\u00e1 peregrinando na diocese de Afogados da Ingazeira ficar\u00e1 em definitivo na Catedral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Do Afogados On-Line Depois de passar cinco meses peregrinando em 23 par\u00f3quias da diocese de Afogados da Ingazeira finalmente a<\/p>\n","protected":false},"author":4,"featured_media":46345,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[47,6147,4839],"class_list":["post-51514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-destaques","tag-imagem-peregrina","tag-nossa-senhora-aparecida"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/51514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=51514"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/51514\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/46345"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=51514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=51514"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=51514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}