{"id":51566,"date":"2016-10-05T07:15:18","date_gmt":"2016-10-05T10:15:18","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=51566"},"modified":"2016-10-05T00:36:15","modified_gmt":"2016-10-05T03:36:15","slug":"tabira-vereador-marcos-crente-agradece-pela-reeleicao","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/tabira-vereador-marcos-crente-agradece-pela-reeleicao\/","title":{"rendered":"Tabira: vereador Marcos Crente agradece pela reelei\u00e7\u00e3o"},"content":{"rendered":"<p>O vereador e presidente da C\u00e2mara de Tabira, Marcos Crente (PSB), usou a imprensa local e as redes sociais para agradecer \u00e0 popula\u00e7\u00e3o tabirense pela sua reelei\u00e7\u00e3o para mais um mandato no legislativo municipal.<\/p>\n<p>\u201cAgrade\u00e7o a minha fam\u00edlia, amigos e especialmente a sociedade tabirense que votou com consci\u00eancia e nos deu a oportunidade de permanecer por mais quatro anos defendendo os interesses do nosso povo. Tenho certeza que com a experi\u00eancia adquirida vamos trabalhar ainda mais pelo bem de Tabira\u201d, disse.<\/p>\n<p>Em seu primeiro mandato, Marcos Crente foi autor de projetos e conquistas importantes para Tabira. Cobrou a equipara\u00e7\u00e3o salarial para os servidores p\u00fablicos, criou o projeto que garante horas-m\u00e1quina para os agricultores, conseguiu a instala\u00e7\u00e3o de uma balan\u00e7a no curral do gado, economizou cem mil reais para a compra de um \u00f4nibus para o TFD e est\u00e1 lutando pelo abastecimento de \u00e1gua na Arara, entre outras iniciativas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O vereador e presidente da C\u00e2mara de Tabira, Marcos Crente (PSB), usou a imprensa local e as redes sociais para<\/p>\n","protected":false},"author":4,"featured_media":51567,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[47,5098,529,38],"class_list":["post-51566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-destaques","tag-eleicoes-2016","tag-marcos-crente","tag-tabira"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/51566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=51566"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/51566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/51567"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=51566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=51566"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=51566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}