{"id":51617,"date":"2016-10-06T09:01:52","date_gmt":"2016-10-06T12:01:52","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=51617"},"modified":"2016-10-06T09:01:52","modified_gmt":"2016-10-06T12:01:52","slug":"mais-cobranca-da-sociedade-grupo-de-zap-movimento-de-empresarios-e-mp-cobram-recuo-dos-vereadores-sobre-aumento","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/mais-cobranca-da-sociedade-grupo-de-zap-movimento-de-empresarios-e-mp-cobram-recuo-dos-vereadores-sobre-aumento\/","title":{"rendered":"Mais cobran\u00e7a da sociedade: grupo de zap, movimento de empres\u00e1rios e MP cobram recuo dos vereadores sobre aumento"},"content":{"rendered":"<p>Mais movimentos puxados pela opini\u00e3o p\u00fablica est\u00e3o cobrando uma posi\u00e7\u00e3o da C\u00e2mara de Vereadores de Afogados da Ingazeira por conta do aumento de sal\u00e1rios aprovado pela Mesa Diretora em resolu\u00e7\u00e3o, para o per\u00edodo 2017-2010.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-51618 alignleft\" src=\"http:\/\/www.radiopajeu.com.br\/portal\/wp-content\/uploads\/2016\/10\/6f6621ab-a9e4-4ad2-9867-c670e8a941d2-225x400.jpg\" alt=\"6f6621ab-a9e4-4ad2-9867-c670e8a941d2-225x400\" width=\"225\" height=\"400\" srcset=\"http:\/\/www.radiopajeu.com.br\/portal\/wp-content\/uploads\/2016\/10\/6f6621ab-a9e4-4ad2-9867-c670e8a941d2-225x400.jpg 225w, http:\/\/www.radiopajeu.com.br\/portal\/wp-content\/uploads\/2016\/10\/6f6621ab-a9e4-4ad2-9867-c670e8a941d2-225x400-169x300.jpg 169w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/>Ontem, um grupo de WhattsApp batizado de \u201cContra o Aumento\u201d, foi criado. J\u00e1 conta com mais de cem participantes. O grupo discute alternativas de press\u00e3o junto aos vereadores para que recuem da decis\u00e3o tomada em agosto.<\/p>\n<p>Tamb\u00e9m esta semana, o promotor L\u00facio Luiz de Almeida Neto enviou of\u00edcio \u00e0 C\u00e2mara de Vereadores solicitando informa\u00e7\u00f5es \u00e0 luz do princ\u00edpio da transpar\u00eancia, considerando a import\u00e2ncia da participa\u00e7\u00e3o popular em determinadas mat\u00e9rias, para que, no prazo de dois dias, a C\u00e2mara de Vereadores informe qual foi o fundamento normativo do aumento.<\/p>\n<p>Ontem, um grupo de empres\u00e1rios e de setores da popula\u00e7\u00e3o, que passou a ser batizado de Movimento Fiscaliza Afogados, se reuniu para provocar e debater o tema. Prometem estar segunda na R\u00e1dio Paje\u00fa para discutir e amadurecer \u00a0algumas ideias a respeito do aumento do sal\u00e1rio dos vereadores. Obviamente, questionam a forma e o pr\u00f3prio aumento.<\/p>\n<p>Ontem , a presidente da Associa\u00e7\u00e3o dos Professores de Afogados da Ingazeira, Leila Albuquerque, criticou duramente a C\u00e2mara. \u201cQuando foi para discutir o pagamento dos nossos quinqu\u00eanios, \u00e0 calada da noite encaminharam um documento que tirava nosso direito. Agora, para aprovar aumento para eles \u00e9 assim. Imagine se o professor pudesse dizer nosso aumento ser\u00e1 de tantos por cento e encaminhar s\u00f3 para Verat\u00e2nia Morais assinar\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-51619\" src=\"http:\/\/www.radiopajeu.com.br\/portal\/wp-content\/uploads\/2016\/10\/c9a15aaa-b9d6-4328-a90a-d9dd21ecd982-768x1024-768x1024.jpg\" alt=\"c9a15aaa-b9d6-4328-a90a-d9dd21ecd982-768x1024\" width=\"618\" height=\"824\" srcset=\"http:\/\/www.radiopajeu.com.br\/portal\/wp-content\/uploads\/2016\/10\/c9a15aaa-b9d6-4328-a90a-d9dd21ecd982-768x1024.jpg 768w, http:\/\/www.radiopajeu.com.br\/portal\/wp-content\/uploads\/2016\/10\/c9a15aaa-b9d6-4328-a90a-d9dd21ecd982-768x1024-225x300.jpg 225w\" sizes=\"auto, (max-width: 618px) 100vw, 618px\" \/><\/p>\n<p>Ela disse que sentiu-se enojada com a vota\u00e7\u00e3o. \u201cS\u00f3 votam pedido de quebra-molas\u201d. A Diretora do Sindrac\u2019s, Maria Auxiliadora, tamb\u00e9m prometeu pressionar os vereadores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mais movimentos puxados pela opini\u00e3o p\u00fablica est\u00e3o cobrando uma posi\u00e7\u00e3o da C\u00e2mara de Vereadores de Afogados da Ingazeira por conta<\/p>\n","protected":false},"author":4,"featured_media":51583,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[15,1522,47,424],"class_list":["post-51617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-afogados-da-ingazeira","tag-camara-de-vereadores","tag-destaques","tag-polemica"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/51617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=51617"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/51617\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/51583"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=51617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=51617"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=51617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}