{"id":53119,"date":"2016-12-03T07:53:37","date_gmt":"2016-12-03T10:53:37","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=53119"},"modified":"2016-12-03T07:53:37","modified_gmt":"2016-12-03T10:53:37","slug":"prefeito-de-afogados-defende-luciano-duque-e-diz-que-sem-garantias-nao-ha-perspectiva-de-samu-andar","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/prefeito-de-afogados-defende-luciano-duque-e-diz-que-sem-garantias-nao-ha-perspectiva-de-samu-andar\/","title":{"rendered":"Prefeito de Afogados defende Luciano Duque e diz que, sem garantias, n\u00e3o h\u00e1 perspectiva de SAMU andar"},"content":{"rendered":"<p>O Prefeito de Afogados da Ingazeira e Presidente Licenciado da AMUPE, Jos\u00e9 Patriota, disse no Debate das Dez na R\u00e1dio Paje\u00fa que, sem garantias de custeio, n\u00e3o tem como o Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia \u2013 SAMU, funcionar no Paje\u00fa. O gestor afirmou que o impasse continua porque n\u00e3o h\u00e1 garantias plenas de contrapartidas de Estado e Governo Federal, atrav\u00e9s do Minist\u00e9rio da Sa\u00fade. \u201dH\u00e1 programas federais que a gente come\u00e7ou como o CAPS e ainda n\u00e3o recebeu contrapartida\u201d, afirmou.<\/p>\n<p>O prefeito tamb\u00e9m defendeu a posi\u00e7\u00e3o do prefeito de Serra Talhada, Luciano Duque, cujo munic\u00edpio sedia a Central de Regula\u00e7\u00e3o do SAMU. Duque j\u00e1 disse que n\u00e3o tem como por o servi\u00e7o para funcionar sem garantias de contrapartida. Com pr\u00e9dio f\u00edsico conclu\u00eddo, h\u00e1 meses, a Central n\u00e3o come\u00e7ou a funcionar, travando o servi\u00e7o. \u201dEle n\u00e3o tem como abrir se os outras n\u00e3o entes fazerem sua parte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Prefeito de Afogados da Ingazeira e Presidente Licenciado da AMUPE, Jos\u00e9 Patriota, disse no Debate das Dez na R\u00e1dio<\/p>\n","protected":false},"author":4,"featured_media":20933,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[47,251,308,108],"class_list":["post-53119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-destaques","tag-jose-patriota","tag-luciano-duque","tag-serra-talhada"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/53119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=53119"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/53119\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/20933"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=53119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=53119"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=53119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}