{"id":5749,"date":"2013-12-20T06:55:02","date_gmt":"2013-12-20T09:55:02","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=5749"},"modified":"2013-12-19T21:42:26","modified_gmt":"2013-12-20T00:42:26","slug":"brasil-fechara-o-ano-em-10o-no-ranking-da-fifa","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/brasil-fechara-o-ano-em-10o-no-ranking-da-fifa\/","title":{"rendered":"Brasil fechar\u00e1 o ano em 10\u00ba no ranking da Fifa"},"content":{"rendered":"<p>Depois de conhecer os seus primeiros advers\u00e1rios na Copa do Mundo de 2014, o Brasil fechar\u00e1 2013 na d\u00e9cima posi\u00e7\u00e3o do ranking da Fifa. O pa\u00eds se manteve na mesma coloca\u00e7\u00e3o do m\u00eas passado e a listagem atualizada pela entidade nesta quinta-feira tamb\u00e9m confirmou a Espanha permanecendo tranquila na lideran\u00e7a, com 1.507 pontos, enquanto a Alemanha segue no segundo lugar, com 1.318.<\/p>\n<p>Nenhuma mudan\u00e7a de posi\u00e7\u00f5es ocorreu no Top 10 em rela\u00e7\u00e3o ao m\u00eas passado, sendo que a \u00fanica novidade do Top 20 foi a entrada da B\u00f3snia-Herzegovina, que estar\u00e1 no Mundial que ser\u00e1 realizado no Brasil e saltou do 21\u00ba para a 19\u00ba posto do ranking. O pa\u00eds ultrapassou Fran\u00e7a e M\u00e9xico, agora respectivamente em 20\u00ba e 21\u00ba lugares.<\/p>\n<p>O pequeno n\u00famero de altera\u00e7\u00f5es de coloca\u00e7\u00f5es no ranking da Fifa j\u00e1 era esperado, pois para esta atualiza\u00e7\u00e3o de dezembro foram levados em conta a disputa de apenas 30 jogos. Ao total no ano, 918 partidas foram consideradas, sendo a maioria delas (415) amistosos e mais de um ter\u00e7o (347) confrontos das Eliminat\u00f3rias da Copa do Mundo de 2014.<\/p>\n<p>Atual campe\u00e3 do mundo, a Espanha terminou pela sexta vez consecutiva um ano na ponta do ranking, confirmando o seu dom\u00ednio no Top 10. Atr\u00e1s da vice-l\u00edder Alemanha, Argentina, Col\u00f4mbia, Portugal, Uruguai, It\u00e1lia, Su\u00ed\u00e7a, Holanda e Brasil, nesta ordem, fecham o grupo dos dez mais bem colocados.<\/p>\n<p>J\u00e1 a Ucr\u00e2nia, que amargou uma dura elimina\u00e7\u00e3o diante da Fran\u00e7a na repescagem das Eliminat\u00f3rias da Copa de 2014, teve como consolo o fato de que foi a sele\u00e7\u00e3o que mais evoluiu neste ano no ranking da Fifa. Com nove vit\u00f3rias, dois empates e s\u00f3 uma derrota, o pa\u00eds somou 312 pontos desde dezembro de 2012, subindo 29 posi\u00e7\u00f5es at\u00e9 terminar 2013 em 18\u00ba lugar. Os Estados Unidos, hoje no 14\u00ba posto da listagem, tamb\u00e9m conseguiram grande ascens\u00e3o ao longo do ano ao somar 237 pontos no per\u00edodo. O mesmo vale para a modesta Arm\u00eania, 35\u00aa colocada ap\u00f3s ganhar mais 259 pontos em rela\u00e7\u00e3o ao que tinha no final de 2012.<\/p>\n<p>A primeira atualiza\u00e7\u00e3o do ranking da Fifa em 2014 ocorrer\u00e1 no dia 16 de janeiro, quando poucas novidades em rela\u00e7\u00e3o a dezembro ser\u00e3o apresentadas na listagem da entidade.<\/p>\n<p>Confira os 20 mais bem colocados do ranking da Fifa:<\/p>\n<p>1) Espanha, 1.507 pontos<\/p>\n<p>2) Alemanha, 1.318<\/p>\n<p>3) Argentina, 1.251<\/p>\n<p>4) Col\u00f4mbia, 1.200<\/p>\n<p>5) Portugal, 1.172<\/p>\n<p>6) Uruguai, 1.132<\/p>\n<p>7) It\u00e1lia, 1.120<\/p>\n<p>8) Su\u00ed\u00e7a, 1.113<\/p>\n<p>9) Holanda, 1.106<\/p>\n<p>10) Brasil, 1.102<\/p>\n<p>11) B\u00e9lgica, 1.098<\/p>\n<p>12) Gr\u00e9cia, 1.055<\/p>\n<p>13) Inglaterra, 1.041<\/p>\n<p>14) Estados Unidos, 1.019<\/p>\n<p>15) Chile, 1.014<\/p>\n<p>16) Cro\u00e1cia, 971<\/p>\n<p>17) Costa do Marfim, 918<\/p>\n<p>18) Ucr\u00e2nia, 907<\/p>\n<p>19) B\u00f3snia-Herzegovina, 899<\/p>\n<p>20) Fran\u00e7a, 893<\/p>\n<p><em><strong>Fonte: Ag\u00eancia Estado<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depois de conhecer os seus primeiros advers\u00e1rios na Copa do Mundo de 2014, o Brasil fechar\u00e1 2013 na d\u00e9cima posi\u00e7\u00e3o<\/p>\n","protected":false},"author":4,"featured_media":5750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[47,524,1273,808],"class_list":["post-5749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-destaques","tag-fifa","tag-rancking","tag-selecao-brasileira"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/5749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=5749"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/5749\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/5750"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=5749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=5749"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=5749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}