{"id":5773,"date":"2013-12-20T08:14:18","date_gmt":"2013-12-20T11:14:18","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=5773"},"modified":"2013-12-20T08:14:18","modified_gmt":"2013-12-20T11:14:18","slug":"mesmo-com-adutora-do-pajeu-tabira-ainda-sofre-com-a-falta-dagua","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/mesmo-com-adutora-do-pajeu-tabira-ainda-sofre-com-a-falta-dagua\/","title":{"rendered":"Mesmo com Adutora do Paje\u00fa Tabira ainda sofre com a falta d\u2019\u00e1gua"},"content":{"rendered":"<p>A t\u00e3o esperada \u00e1gua da Adutora do Paje\u00fa ainda n\u00e3o tirou a cidade de Tabira da crise no abastecimento. Na rua Jurandir Cordeiro s\u00e3o 40 dias sem \u00e1gua; Rua do Posto no Bairro de F\u00e1tima\u00a0 I 30 dias; Travessas I e II da Cohab s\u00e3o 60 dias; Rua Ant\u00f4nio Florentino 30 dias. O abastecimento com carro pipa j\u00e1 foi suspenso dificultando ainda mais a situa\u00e7\u00e3o de muitos moradores da cidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A t\u00e3o esperada \u00e1gua da Adutora do Paje\u00fa ainda n\u00e3o tirou a cidade de Tabira da crise no abastecimento. Na<\/p>\n","protected":false},"author":4,"featured_media":3549,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[19,33,47,38],"class_list":["post-5773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-adutora-do-pajeu","tag-agua","tag-destaques","tag-tabira"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/5773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=5773"}],"version-history":[{"count":0,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/5773\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/3549"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=5773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=5773"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=5773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}