{"id":73391,"date":"2018-08-22T07:55:15","date_gmt":"2018-08-22T10:55:15","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=73391"},"modified":"2018-08-22T07:55:15","modified_gmt":"2018-08-22T10:55:15","slug":"em-debate-na-fiepe-paulo-camara-propoe-pacto-para-geracao-de-novos-empregos","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/em-debate-na-fiepe-paulo-camara-propoe-pacto-para-geracao-de-novos-empregos\/","title":{"rendered":"Em debate na Fiepe, Paulo C\u00e2mara prop\u00f5e pacto para gera\u00e7\u00e3o de novos empregos"},"content":{"rendered":"<p>Convidado pela Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de Pernambuco (Fiepe) para participar do Di\u00e1logo com Candidatos, o governador Paulo C\u00e2mara (PSB) defendeu, nesta ter\u00e7a-feira (21), a forma\u00e7\u00e3o de um pacto pela economia. O objetivo, segundo o socialista, \u00e9 iniciar uma nova etapa de diretrizes para permitir ainda mais avan\u00e7os para Pernambuco, com a atra\u00e7\u00e3o de empreendimentos, o investimento em qualifica\u00e7\u00e3o profissional, a gera\u00e7\u00e3o de mais empregos e o crescimento da economia, que foi afetada pela crise nacional nos \u00faltimos quatro anos.<\/p>\n<p>Paulo C\u00e2mara destacou que, ap\u00f3s estruturar Pernambuco em um per\u00edodo de intensa dificuldade financeira constatada em todo o Pa\u00eds, que permitiu que o Estado continuasse promovendo investimentos e mantendo os servi\u00e7os essenciais para popula\u00e7\u00e3o, \u00e9 necess\u00e1rio firmar novas metas para a economia pernambucana. \u201cTemos que fazer um novo pacto, voltado \u00e0 sociedade e ao setor produtivo, com participa\u00e7\u00e3o do governo. Criar c\u00e2maras setoriais e regionais que enfoquem oportunidades e verifiquem a maneira de retomar empregos que a crise retirou. Pernambuco foi um dos mais afetados pela crise porque tamb\u00e9m estava em pleno crescimento. Temos que fazer um pacto pela nova economia, pela mobiliza\u00e7\u00e3o de empregos\u201d, defendeu o governador.<\/p>\n<p>Paulo C\u00e2mara destacou que Pernambuco precisa ter acesso a fontes de cr\u00e9ditos, que v\u00e3o contribuir para novas a\u00e7\u00f5es. O gestor lembrou que, mesmo num per\u00edodo de tantas dificuldades, 55% dos investimentos feitos no Estado nos \u00faltimos anos foram com recursos pr\u00f3prios. O socialista ainda destacou que o modelo de gest\u00e3o implantado aqui permitiu que Pernambuco fosse considerado uma das quatro unidades federativas mais eficientes do Pa\u00eds.<\/p>\n<p>Aos representantes da Ind\u00fastria, Paulo C\u00e2mara falou sobre as principais a\u00e7\u00f5es feitas no Estado, como a recupera\u00e7\u00e3o de importantes estradas, a exemplo da BR-104, no Agreste, a duplica\u00e7\u00e3o da PE-160, na mesma regi\u00e3o, e a constru\u00e7\u00e3o do Contorno Vi\u00e1rio de Sert\u00e2nia, no Sert\u00e3o do Moxot\u00f3. Tamb\u00e9m falou sobre a viabiliza\u00e7\u00e3o de importantes obras de recursos h\u00eddricos, essenciais para o desenvolvimento econ\u00f4mico pernambucano.<\/p>\n<p>Em seu pronunciamento, o governador citou tamb\u00e9m as principais a\u00e7\u00f5es para o incentivo ao desenvolvimento da ind\u00fastria, a exemplo a consolida\u00e7\u00e3o da Lei Geral do ICMS, a institui\u00e7\u00e3o do Programa de Est\u00edmulo \u00e0 Ind\u00fastria (Proind), a simplifica\u00e7\u00e3o dos procedimentos de fiscaliza\u00e7\u00e3o nos postos fiscais e ado\u00e7\u00e3o do SPED nacional.<\/p>\n<p>Durante o debate, o governador respondeu a perguntas de representantes do setor sobre a cria\u00e7\u00e3o de novos empregos e a manuten\u00e7\u00e3o das estradas pernambucanas. \u201cVamos continuar a buscar avan\u00e7os nos incentivos fiscais para garantir principalmente a produ\u00e7\u00e3o de emprego. Tivemos avan\u00e7os importantes. Abrimos novas usinas, garantimos benef\u00edcios para o Polo de Confec\u00e7\u00f5es do Agreste, para o Polo Gesseiro, com a diminui\u00e7\u00e3o do ICMS, e tamb\u00e9m benef\u00edcios para o Polo da Avicultura, al\u00e9m do hub da Azul\u201d, citou.<\/p>\n<p>O presidente da Fiepe, Ricardo Essinger, agradeceu a presen\u00e7a do governador Paulo C\u00e2mara no debate e destacou que o objetivo do encontro, que tem sido realizado nas \u00faltimas elei\u00e7\u00f5es, \u00e9 enriquecer o debate sobre o setor em Pernambuco. \u201cN\u00f3s, industriais pernambucanos, estaremos aqui, trabalhando, produzindo e contribuindo para o crescimento do estado. Da parte do Sistema Fiepe, os futuros gestores encontrar\u00e3o sempre um aliado, parceiro interessado, dedicado e devotado \u00e0s a\u00e7\u00f5es pertinentes ao desenvolvimento das atividades industriais e ao bem-estar da popula\u00e7\u00e3o\u201d, declarou o dirigente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Convidado pela Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de Pernambuco (Fiepe) para participar do Di\u00e1logo com Candidatos, o governador Paulo C\u00e2mara<\/p>\n","protected":false},"author":4,"featured_media":73392,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[6309,1826],"class_list":["post-73391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-eleicoes-2018","tag-paulo-camara"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/73391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=73391"}],"version-history":[{"count":1,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/73391\/revisions"}],"predecessor-version":[{"id":73393,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/73391\/revisions\/73393"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/73392"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=73391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=73391"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=73391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}