{"id":75927,"date":"2018-12-19T15:36:53","date_gmt":"2018-12-19T18:36:53","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=75927"},"modified":"2018-12-19T15:36:53","modified_gmt":"2018-12-19T18:36:53","slug":"parecer-de-armando-aumenta-controle-das-estatais","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/parecer-de-armando-aumenta-controle-das-estatais\/","title":{"rendered":"Parecer de Armando aumenta controle das estatais"},"content":{"rendered":"<p>A Comiss\u00e3o de Transpar\u00eancia e Fiscaliza\u00e7\u00e3o aprovou hoje (quarta, 19) parecer do senador Armando Monteiro (PTB-PE) a projeto de lei que obriga os governos federal e estaduais e as prefeituras a divulgarem, anualmente, avalia\u00e7\u00e3o do cumprimento dos objetivos de suas empresas que exer\u00e7am atividade econ\u00f4mica. O projeto seguir\u00e1 direto ao exame da C\u00e2mara dos Deputados.<\/p>\n<p>A iniciativa, que aperfei\u00e7oa o Estatuto das Empresas Estatais, em vigor desde 2016, justifica ser importante, como ressalta o parecer, que \u201co \u00f3rg\u00e3o supervisor da estatal d\u00ea publicidade, a cada ano, aos objetivos de pol\u00edticas p\u00fablicas compat\u00edveis com os imperativos de seguran\u00e7a nacional ou com os relevantes interesses coletivos que justificam a manuten\u00e7\u00e3o das atividades da empresa\u201d.<\/p>\n<p>Armando Monteiro explica, em seu parecer, que a explora\u00e7\u00e3o de atividade econ\u00f4mica em sentido estrito pelo Estado s\u00f3 tem sentido para atender a imperativos de seguran\u00e7a nacional ou relevante interesse p\u00fablico. \u2018A atua\u00e7\u00e3o das empresas governamentais n\u00e3o pode se guiar apenas por uma rela\u00e7\u00e3o de custo-benef\u00edcio das pr\u00f3prias empresas, pelos impactos de suas decis\u00f5es sobre as empresas privadas e a coletividade\u201d, conclui o senador petebista.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o de Transpar\u00eancia e Fiscaliza\u00e7\u00e3o aprovou hoje (quarta, 19) parecer do senador Armando Monteiro (PTB-PE) a projeto de lei<\/p>\n","protected":false},"author":4,"featured_media":75928,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[177,438,8974,8975,190],"class_list":["post-75927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-armando-monteiro","tag-camara","tag-estatais","tag-parecer","tag-senado"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/75927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=75927"}],"version-history":[{"count":1,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/75927\/revisions"}],"predecessor-version":[{"id":75929,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/75927\/revisions\/75929"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/75928"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=75927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=75927"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=75927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}