{"id":77450,"date":"2019-04-17T07:41:38","date_gmt":"2019-04-17T10:41:38","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=77450"},"modified":"2019-04-17T07:41:38","modified_gmt":"2019-04-17T10:41:38","slug":"senadores-vao-pedir-impeachment-de-dias-toffoli-e-alexandre-de-moraes","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/senadores-vao-pedir-impeachment-de-dias-toffoli-e-alexandre-de-moraes\/","title":{"rendered":"Senadores v\u00e3o pedir impeachment de Dias Toffoli e Alexandre de Moraes"},"content":{"rendered":"<p><em>Do Congresso em Foco<\/em><\/p>\n<p>O senador Alessandro Vieira (Cidadania-SE) afirmou, nesta ter\u00e7a-feira (16), que pedir\u00e1 o impeachment do presidente do STF (Supremo Tribunal Federal), Dias Toffoli, e do ministro Alexandre de Moraes, por crime de responsabilidade e abuso de autoridade. Outros senadores, como Randolfe Rodrigues (Rede-AP) e Lasier Martins (PODE-RS), j\u00e1 confirmam que v\u00e3o assinar o pedido junto com Vieira.<\/p>\n<p>Toffoli e Moraes s\u00e3o respons\u00e1veis, na Corte, por um inqu\u00e9rito aberto pelo pr\u00f3prio STF, h\u00e1 um m\u00eas, para apurar ataques \u00e0 honra dos ministros do tribunal. A procuradora-geral da Rep\u00fablica (PGR), Raquel Dodge, se manifestou nesta ter\u00e7a pelo arquivamento da investiga\u00e7\u00e3o, que tem sido alvo crescente de protestos de autoridades e nas redes sociais desde a \u00faltima segunda, quando Moraes determinou censura a uma reportagem que citava o presidente da Corte.<\/p>\n<p>Para Vieira, que tamb\u00e9m \u00e9 o autor do pedido de cria\u00e7\u00e3o de uma CPI para investigar tribunais superiores (a chamada CPI Lava Toga), a investiga\u00e7\u00e3o cometeu ilegalidades na \u00faltima segunda (15), ao censurar uma reportagem da revista Cruso\u00e9 e do site O Antagonista que citava Toffoli, e tamb\u00e9m nesta ter\u00e7a, ao ordenar buscas relacionadas a sete pessoas que &#8220;apenas emitiram opini\u00f5es em redes sociais&#8221; contra o Supremo, na avalia\u00e7\u00e3o do parlamentar.<\/p>\n<p>A manifesta\u00e7\u00e3o de Dodge para arquivar o inqu\u00e9rito significa, segundo Vieira, um freio a um caso de abuso de poder. Na avalia\u00e7\u00e3o do senador, os dois ministros usurparam de sua compet\u00eancia. &#8220;O que Toffoli e Alexandre de Moraes foi criminoso&#8221;, critica.<\/p>\n<p>O senador afirma que o Supremo se apequena ao manter os dois ministros no cargo. &#8220;O Supremo fica do tamanho desses ministros, inexistente praticamente. Fica todo mundo no mesmo saco, comprometendo as institui\u00e7\u00f5es&#8221;, afirma.<\/p>\n<p>Assim que for protocolado, este ser\u00e1 o d\u00e9cimo terceiro pedido de impeachment de ministros do Supremo protocolado no Senado. Um levantamento do Congresso em Foco, publicado na \u00faltima quinta, mostrou que s\u00f3 neste ano j\u00e1 haviam sido protocolados sete pedidos, somados a outros cinco que ainda est\u00e3o em tramita\u00e7\u00e3o. Toffoli e o ministro Gilmar Mendes s\u00e3o os principais alvos, com tr\u00eas pedidos individuais contra cada um. (Veja a lista com todos os pedidos ao final da mat\u00e9ria).<\/p>\n<p>A decis\u00e3o de dar andamento a algum destes pedidos cabe exclusivamente ao presidente do Senado, Davi Alcolumbre (DEM-AP). Um projeto de lei apresentado por Lasier Martins, no entanto, busca desengavetar as den\u00fancias. Pela proposta, Alcolumbre passaria a ter um prazo de 15 dias para emitir parecer favor\u00e1vel ou contr\u00e1rio \u00e0 aceita\u00e7\u00e3o de pedido de impeachment, e a decis\u00e3o final caberia ao plen\u00e1rio.<\/p>\n<p><strong>CPI Lava Toga<\/strong><\/p>\n<p>Alessandro Vieira considera que uma CPI para investigar os tribunais superiores se torna, a cada dia, mais urgente e necess\u00e1ria.<\/p>\n<p>&#8220;Precisamos resgatar a credibilidade da mais alta corte do Judici\u00e1rio brasileiro. \u00c9 preciso que a press\u00e3o popular chegue ao Congresso&#8221;, defende. Embora comemore a decis\u00e3o de Dodge, o senador, que \u00e9 delegado da Pol\u00edcia Federal, diz ver com estranheza o fato de a procuradora-geral ter determinado, em vez de recomendado, o arquivamento do inqu\u00e9rito aberto por Toffoli.<\/p>\n<p>&#8220;Quem teria de arquivar era o Judici\u00e1rio, n\u00e3o o Minist\u00e9rio P\u00fablico. Enfim, est\u00e1 tudo errado&#8221;, diz. &#8220;Qualquer estudante de Direito sabia que esse inqu\u00e9rito era absolutamente arbitr\u00e1rio e equivocado&#8221;, acrescenta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Do Congresso em Foco O senador Alessandro Vieira (Cidadania-SE) afirmou, nesta ter\u00e7a-feira (16), que pedir\u00e1 o impeachment do presidente do<\/p>\n","protected":false},"author":4,"featured_media":77451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[9211,5147,1861,155],"class_list":["post-77450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-cpi-lava-toga","tag-impeachement","tag-senado-federal","tag-stf"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/77450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=77450"}],"version-history":[{"count":1,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/77450\/revisions"}],"predecessor-version":[{"id":77452,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/77450\/revisions\/77452"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/77451"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=77450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=77450"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=77450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}