{"id":78320,"date":"2019-06-04T07:41:56","date_gmt":"2019-06-04T10:41:56","guid":{"rendered":"http:\/\/www.radiopajeu.com.br\/portal\/?p=78320"},"modified":"2019-06-04T07:41:56","modified_gmt":"2019-06-04T10:41:56","slug":"corpo-encontrado-dentro-de-acude-em-sje-veja-esta-e-outras-ocorrencias","status":"publish","type":"post","link":"http:\/\/www.radiopajeu.com.br\/portal\/corpo-encontrado-dentro-de-acude-em-sje-veja-esta-e-outras-ocorrencias\/","title":{"rendered":"Corpo encontrado dentro de a\u00e7ude em SJE. Veja esta e outras ocorr\u00eancias"},"content":{"rendered":"<p><strong>DOIS FERIDOS EM ACIDENTE DE MOTO EM SANTA TEREZINHA &#8211;<\/strong> Durante a realiza\u00e7\u00e3o da Opera\u00e7\u00e3o Madrugada Segura, a GT local foi informada que havia acontecido um acidente de tr\u00e2nsito na PE 285, km 01, sa\u00edda para Imaculada, em Santa Terezinha. No local, o policiamento constatou que o condutor da motocicleta (v\u00edtima 01) J. A. C., 23 anos, estado civil n\u00e3o informado, agricultor, ao trafegar em sua motocicleta Honda\/CG 150 Titan, cor preta, ano 2013\/2014, perdeu o controle do ve\u00edculo vindo a tombar, juntamente com o passageiro (v\u00edtima 02) H. N. S., 19 anos, estado civil n\u00e3o informado, agricultor. As v\u00edtimas sofreram les\u00f5es pelo corpo e foram socorridas por populares para o hospital local.<\/p>\n<p><strong>AGRICULTOR DESCUMPRE MEDIDA PROTETIVA NO SANTO ANT\u00d4NIO &#8211;<\/strong> A GT foi acionada pela Central de Opera\u00e7\u00f5es, para averiguar a quebra de medida protetiva no S\u00edtio Santo Ant\u00f4nio 2, Zona Rural de Afogados da Ingazeira.<\/p>\n<p>No local constatou a veracidade dos fatos e que o imputado E. M. G., solteiro, 33 anos, agricultor, se encontrava a aproximadamente uns (100) cem metros de dist\u00e2ncia da v\u00edtima M. A. S., 40 anos, solteira. A medida protetiva que a v\u00edtima tem contra o imputado, pro\u00edbe ele de aproximar-se dela a uma dist\u00e2ncia de (200) duzentos metros.<\/p>\n<p>A v\u00edtima relatou que faz v\u00e1rios dias o imputado vem descumprindo tal medida. Diante dos fatos as partes foram encaminhadas \u00e0 Delegacia da Mulher, onde o imputado vai ser autuado em flagrante delito.<\/p>\n<p><strong>CORPO ENCONTRADO DENTRO DE A\u00c7UDE EM SJE &#8211; <\/strong>A GT ordin\u00e1ria foi informada por uma testemunha, que havia um corpo boiando dentro do a\u00e7ude da comunidade do S\u00edtio Pau Leite de S\u00e3o Jos\u00e9 do Egito. Em seguida o policiamento foi at\u00e9 o local indicado juntamente com as equipes da Pol\u00edcia Civil e do Corpo de Bombeiros Militar.<\/p>\n<p>Na oportunidade o corpo da v\u00edtima J. E. A. S., 46 anos, solteiro, agricultor, morador do S\u00edtio Bara\u00fanas, foi retirado do a\u00e7ude pela equipe de Bombeiros Militares, onde foi realizada Per\u00edcia M\u00e9dica pela Equipe do Instituto de Criminal\u00edstica.<\/p>\n<p>Segundo a irm\u00e3 da v\u00edtima, a mesma sofria com ataques de epilepsia alco\u00f3lica e que aparentemente veio a falecer por afogamento. A v\u00edtima estava desaparecida desde o \u00faltimo s\u00e1bado.<\/p>\n<p>A ocorr\u00eancia foi registrada na DEPOL local, onde ser\u00e1 instaurado inqu\u00e9rito para investigar a morte e o corpo encaminhado para o IML em Caruaru, para identificar a causa morte.<\/p>\n<p><strong>MEC\u00c2NICO SEM HABILITA\u00c7\u00c3O \u00c9 FLAGRADO EMPINANDO MOTO EM TUPARETAMA &#8211;<\/strong> A GT ordin\u00e1ria estava em rondas no bairro Bom Jesus, Tuparetama, quando o imputado D. A. S., 22 anos, solteiro, mec\u00e2nico de moto, saiu de uma rua transversal em uma motocicleta Honda CG 125 FAN, cor preta, ano 2008, placa MOW-6935 desenvolvendo alta velocidade e empinando onde transitavam os pedestres, causando riscos \u00e0s pessoas.<\/p>\n<p>A GT fez o acompanhamento do imputado conseguindo intercept\u00e1-lo. Ao solicitar os documentos de porte obrigat\u00f3rio, o imputado disse s\u00f3 possuir a documenta\u00e7\u00e3o da motocicleta, mas n\u00e3o possuir CNH.<\/p>\n<p>Mediante a situa\u00e7\u00e3o e pelo fato de o imputado est\u00e1 causando perigo de dano \u00e0s pessoas que ali transitavam, o imputado foi conduzido \u00e0 DPC local, onde responder\u00e1 a um T.C.O.<\/p>\n<p><strong>PERTURBA\u00c7\u00c3O DE SOSSEGO E AMEA\u00c7AS EM TABIRA &#8211;\u00a0<\/strong> Durante a opera\u00e7\u00e3o Duas Rodas, o policiamento foi solicitado via liga\u00e7\u00e3o telef\u00f4nica pela v\u00edtima V. F.\u00a0 N., 39 anos, agricultor, relatando sobre um som vizinho a sua casa que h\u00e1 dias vinha perturbando o sossego e que j\u00e1 teria falado v\u00e1rias vezes com os propriet\u00e1rios mais de nada adiantou.<\/p>\n<p>Ao chegar no local a v\u00edtima se prontificou em prestar a queixa formal na delegacia, onde na ocasi\u00e3o foi dado voz de pris\u00e3o aos propriet\u00e1rios do som, momento este em que os imputados come\u00e7aram desacatar o policiamento e vindo a resistir a pris\u00e3o, sendo necess\u00e1rio fazer o uso da for\u00e7a para conter os imputados J. P. S. M., 24 anos, solteiro, agricultor e V. L. P. S. M., demais dados n\u00e3o informados, como foi necess\u00e1rio o uso de algemas para preservar a integridade f\u00edsica dos imputados e do efetivo.<\/p>\n<p>Vale salientar ainda que os imputados amea\u00e7aram a v\u00edtima que foi denunciante na frente do efetivo policial. Diante dos fatos os imputados foram apresentados na D.P local onde foi lavrado um T.C.O em desfavor dos mesmos.<\/p>\n<p><strong>AGRICULTOR \u00c9 FLAGRADO COM FACA EM FESTA NA ZONA RURAL &#8211;<\/strong> Quando a GT realizava rondas com abordagens no p\u00e1tio de Festa de Santo Ant\u00f4nio,\u00a0 depararam-se com o imputado J. A. B. S., 51 anos, solteiro, agricultor, morador do Bairro Santa Luzia, Carna\u00edba, o qual estava com uma faca na cintura, medindo aproximadamente 08 (oito) polegadas. O policiamento imobilizou o imputado e o conduziu juntamente com a faca peixeira \u00e0 DP local, onde o mesmo responder\u00e1 a um TCO.<\/p>\n<p><strong>MORADOR DE RUA SE ENVOLVE EM CONFUS\u00c3O NA PRA\u00c7A ARRUDA C\u00c2MARA &#8211;<\/strong> Ap\u00f3s determina\u00e7\u00e3o da Central de Opera\u00e7\u00f5es, o efetivo deslocou-se a Pra\u00e7a Arrruda C\u00e2mara, Centro, pois estava ocorrendo uma confus\u00e3o. No local, mantiveram contato com os envolvidos, onde a v\u00edtima J. E. da S., divorciado, 42 anos, aut\u00f4nomo, morador do Bairro COHAB, relatou que j\u00e1 existia um desentendimento entre ela e o imputado M. P. da S., solteiro, 35 anos, desocupado, Morador de rua.<\/p>\n<p>Que nesta data, o imputado lhe agrediu com um peda\u00e7o de madeira, causando-lhe uma les\u00e3o na cabe\u00e7a e outra no bra\u00e7o direito. Com o imputado foram encontradas 04 embalagens de cola (garrafas e latinha). Na presen\u00e7a do efetivo, o imputado amea\u00e7ou a v\u00edtima, dizendo que iria atear fogo no seu corpo e em seu barraco. Diante dos fatos expostos, as partes foram encaminhadas \u00e0 DPC local, onde o imputado responder\u00e1 a um TCO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DOIS FERIDOS EM ACIDENTE DE MOTO EM SANTA TEREZINHA &#8211; Durante a realiza\u00e7\u00e3o da Opera\u00e7\u00e3o Madrugada Segura, a GT local<\/p>\n","protected":false},"author":4,"featured_media":69903,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[5,91,7994,27,7954],"class_list":["post-78320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-acidente","tag-agressao","tag-medida-protetiva","tag-morte","tag-perturbacao-de-sossego"],"_links":{"self":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/78320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/comments?post=78320"}],"version-history":[{"count":1,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/78320\/revisions"}],"predecessor-version":[{"id":78321,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/posts\/78320\/revisions\/78321"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media\/69903"}],"wp:attachment":[{"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/media?parent=78320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/categories?post=78320"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiopajeu.com.br\/portal\/wp-json\/wp\/v2\/tags?post=78320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}